{"id":65820,"date":"2026-07-14T21:54:12","date_gmt":"2026-07-15T00:54:12","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=65820"},"modified":"2026-07-14T21:54:15","modified_gmt":"2026-07-15T00:54:15","slug":"piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/","title":{"rendered":"Piacquad\u00edo: Si el Remediar no est\u00e1 llegando a los CAPS es porque Provincia \u201clo est\u00e1 reteniendo\u201d"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-3021333267\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><strong><em>La concejal de Integridad, Vanesa Piaqcuad\u00edo junto al ministro de Salud de la Naci\u00f3n, Mario Lugones<\/em><\/strong><\/p>\n\n\n\n<p>La concejal tresarroyense de Integridad, Vanesa Piacquadio, brind\u00f3 detalles de la reuni\u00f3n que mantuvo con el ministro de Salud de la Naci\u00f3n, Mario Lugones, en la que abord\u00f3 la continuidad del Plan Remediar, el suministro de medicamentos y la posibilidad de gestionar futuras capacitaciones para el personal sanitario de Tres Arroyos.<\/p>\n\n\n\n<p>En di\u00e1logo con Cosas que pasan por Onda Uno, la edil explic\u00f3 que el encuentro surgi\u00f3 con el objetivo de plantear inquietudes sobre la provisi\u00f3n de medicamentos. Seg\u00fan indic\u00f3, desde el Ministerio le confirmaron que el Plan Remediar continuar\u00e1 vigente hasta diciembre, cuando ser\u00e1 reemplazado por un nuevo esquema.<\/p>\n\n\n\n<p><br>&#8220;La medicaci\u00f3n va a estar hasta el mes de diciembre y despu\u00e9s de diciembre eso se va a reconvertir&#8221;, se\u00f1al\u00f3 Piacquadio, quien agreg\u00f3 que la prioridad estar\u00e1 puesta en los medicamentos para tratamientos cardiovasculares y oncol\u00f3gicos.<\/p>\n\n\n\n<p>Respecto a las denuncias por la falta de medicamentos en algunos centros de salud, explic\u00f3 que, de acuerdo con la informaci\u00f3n recibida, Naci\u00f3n entrega los insumos a la Provincia, que luego debe distribuirlos a los municipios.<\/p>\n\n\n\n<p>&#8220;Si el Plan Remediar no est\u00e1 llegando a los CAPS es porque nosotros a Provincia lo estamos entregando en tiempo y forma. A lo mejor es Provincia la que lo est\u00e1 reteniendo y no est\u00e1 llegando a los municipios&#8221;, afirm\u00f3 al transmitir la respuesta que recibi\u00f3 durante el encuentro.<\/p>\n\n\n\n<p>Piacquadio aclar\u00f3 que los insumos destinados a hospitales provinciales son competencia de la Provincia de Buenos Aires, mientras que el programa nacional est\u00e1 orientado a abastecer a los Centros de Atenci\u00f3n Primaria de la Salud (CAPS).<\/p>\n\n\n\n<p>Consultada sobre el motivo de su viaje a Buenos Aires, la concejal explic\u00f3 que se trat\u00f3 de una agenda de gestiones y descart\u00f3 que estuviera vinculada con una estrategia electoral.<\/p>\n\n\n\n<p>&#8220;Mi prioridad es gestionar para Tres Arroyos&#8221;, sostuvo. Adem\u00e1s, se\u00f1al\u00f3 que mantiene contactos con funcionarios nacionales y que continuar\u00e1 realizando gestiones &#8220;pensando en qu\u00e9 se puede aportar para mejorar el distrito&#8221;.<\/p>\n\n\n\n<p>Durante la reuni\u00f3n tambi\u00e9n solicit\u00f3 la posibilidad de gestionar capacitaciones para m\u00e9dicos y enfermeros del sistema de salud local. Si bien le informaron que actualmente no hay programas disponibles, indic\u00f3 que el pedido qued\u00f3 planteado para futuras convocatorias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La concejal de Integridad, Vanesa Piaqcuad\u00edo junto al ministro de Salud de la Naci\u00f3n, Mario Lugones La concejal tresarroyense de Integridad, Vanesa Piacquadio, brind\u00f3 detalles de la reuni\u00f3n que mantuvo con el ministro de Salud de la Naci\u00f3n, Mario Lugones, en la que abord\u00f3 la continuidad del Plan Remediar, el suministro de medicamentos y la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":65821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-65820","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Piacquad\u00edo: Si el Remediar no est\u00e1 llegando a los CAPS es porque Provincia \u201clo est\u00e1 reteniendo\u201d - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piacquad\u00edo: Si el Remediar no est\u00e1 llegando a los CAPS es porque Provincia \u201clo est\u00e1 reteniendo\u201d - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"La concejal de Integridad, Vanesa Piaqcuad\u00edo junto al ministro de Salud de la Naci\u00f3n, Mario Lugones La concejal tresarroyense de Integridad, Vanesa Piacquadio, brind\u00f3 detalles de la reuni\u00f3n que mantuvo con el ministro de Salud de la Naci\u00f3n, Mario Lugones, en la que abord\u00f3 la continuidad del Plan Remediar, el suministro de medicamentos y la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T00:54:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T00:54:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-21.50.41.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/\",\"name\":\"Piacquad\u00edo: Si el Remediar no est\u00e1 llegando a los CAPS es porque Provincia \u201clo est\u00e1 reteniendo\u201d - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-21.50.41.jpeg\",\"datePublished\":\"2026-07-15T00:54:12+00:00\",\"dateModified\":\"2026-07-15T00:54:15+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-21.50.41.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-21.50.41.jpeg\",\"width\":720,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piacquad\u00edo: Si el Remediar no est\u00e1 llegando a los CAPS es porque Provincia \u201clo est\u00e1 reteniendo\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piacquad\u00edo: Si el Remediar no est\u00e1 llegando a los CAPS es porque Provincia \u201clo est\u00e1 reteniendo\u201d - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/","og_locale":"es_ES","og_type":"article","og_title":"Piacquad\u00edo: Si el Remediar no est\u00e1 llegando a los CAPS es porque Provincia \u201clo est\u00e1 reteniendo\u201d - 103.9 fm","og_description":"La concejal de Integridad, Vanesa Piaqcuad\u00edo junto al ministro de Salud de la Naci\u00f3n, Mario Lugones La concejal tresarroyense de Integridad, Vanesa Piacquadio, brind\u00f3 detalles de la reuni\u00f3n que mantuvo con el ministro de Salud de la Naci\u00f3n, Mario Lugones, en la que abord\u00f3 la continuidad del Plan Remediar, el suministro de medicamentos y la [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2026-07-15T00:54:12+00:00","article_modified_time":"2026-07-15T00:54:15+00:00","og_image":[{"width":720,"height":1280,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-21.50.41.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/","url":"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/","name":"Piacquad\u00edo: Si el Remediar no est\u00e1 llegando a los CAPS es porque Provincia \u201clo est\u00e1 reteniendo\u201d - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-21.50.41.jpeg","datePublished":"2026-07-15T00:54:12+00:00","dateModified":"2026-07-15T00:54:15+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-21.50.41.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-21.50.41.jpeg","width":720,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/07\/14\/piacquadio-si-el-remediar-no-esta-llegando-a-los-caps-es-porque-provincia-lo-esta-reteniendo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Piacquad\u00edo: Si el Remediar no est\u00e1 llegando a los CAPS es porque Provincia \u201clo est\u00e1 reteniendo\u201d"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-21.50.41.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=65820"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65820\/revisions"}],"predecessor-version":[{"id":65822,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65820\/revisions\/65822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/65821"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=65820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=65820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=65820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}