{"id":65123,"date":"2026-06-02T19:51:18","date_gmt":"2026-06-02T22:51:18","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=65123"},"modified":"2026-06-02T19:51:24","modified_gmt":"2026-06-02T22:51:24","slug":"piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/","title":{"rendered":"Piden informaci\u00f3n por el estado de alimentos escolares y cuestionan la situaci\u00f3n de Reta"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-18553329\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>La concejal de la Coalici\u00f3n C\u00edvica, Cecilia del Aguila, confirm\u00f3 que present\u00f3 un pedido de informes al Consejo Escolar luego de las denuncias difundidas en redes sociales sobre presuntas irregularidades en alimentos entregados en establecimientos educativos del distrito.<\/p>\n\n\n\n<p>En Cosas que pasan, explic\u00f3 que la iniciativa surgi\u00f3 a partir de la preocupaci\u00f3n manifestada por familias y vecinos.<br>\u201cEs un tema muy sensible. Son cosas que uno no puede dejar pasar\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Seg\u00fan indic\u00f3, el pedido busca conocer qu\u00e9 ocurri\u00f3 y cu\u00e1les fueron las actuaciones realizadas por las autoridades correspondientes.<\/p>\n\n\n\n<p>\u201cSolicitamos que una vez finalizada la investigaci\u00f3n tambi\u00e9n nos transmitan la informaci\u00f3n para poder llevar tranquilidad a la poblaci\u00f3n\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Del Aguila aclar\u00f3 que, hasta el momento, no cuentan con una confirmaci\u00f3n oficial sobre lo ocurrido. \u201cNo puedo dar fe de nada porque todav\u00eda no tenemos respuesta del Consejo Escolar\u201d, expres\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s sostuvo que esperan que la situaci\u00f3n sea investigada con seriedad y remarc\u00f3 que tambi\u00e9n intervienen equipos directivos e inspectores.<\/p>\n\n\n\n<p>Por otra parte, la concejal tambi\u00e9n se refiri\u00f3 al reciente cambio de delegado en Reta, tras la salida de Diego Zyncenko y la designaci\u00f3n interina de Daniel Civetta.<\/p>\n\n\n\n<p>En ese sentido, fue muy cr\u00edtica con la gesti\u00f3n que se ven\u00eda desarrollando en la localidad.<br>\u201cReta es un desastre\u201d, afirm\u00f3 durante la entrevista.<\/p>\n\n\n\n<p>Del Aguila asegur\u00f3 que desde hace tiempo vienen reclamando mayor acompa\u00f1amiento municipal para las localidades del distrito y se\u00f1al\u00f3 problemas vinculados al estado de las calles, desag\u00fces, mantenimiento y servicios.<br>\u201cSon localidades que necesitan planificaci\u00f3n y presencia permanente del municipio\u201d, indic\u00f3.<\/p>\n\n\n\n<p>Tambi\u00e9n cuestion\u00f3 la falta de recursos durante la gesti\u00f3n anterior y asegur\u00f3 que ahora comenzaron a aparecer maquinarias y trabajos que antes no se realizaban.<\/p>\n\n\n\n<p>\u201c\u00bfPor qu\u00e9 llegar a este punto para empezar a solucionar las cosas?\u201d, se pregunt\u00f3.<\/p>\n\n\n\n<p>La edil sostuvo adem\u00e1s que desde su espacio acompa\u00f1aron distintos reclamos vinculados a Reta durante los \u00faltimos a\u00f1os. \u201cHemos presentado proyectos y acompa\u00f1ado pedidos permanentemente\u201d, expres\u00f3.<\/p>\n\n\n\n<p>En el cierre consider\u00f3 que las localidades del distrito \u201cmerecen atenci\u00f3n y gesti\u00f3n constante\u201d y pidi\u00f3 que no sean tratadas \u201ccomo ciudadanos de segunda categor\u00eda\u201d.<\/p>\n\n\n\n<p>Pod\u00e9s escuchar la nota completa en el siguiente link:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"UlqwW9aAVx0\"><iframe loading=\"lazy\" title=\"Onda Uno 103.9 en vivo\" width=\"696\" height=\"392\" data-src=\"https:\/\/www.youtube.com\/embed\/UlqwW9aAVx0?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La concejal de la Coalici\u00f3n C\u00edvica, Cecilia del Aguila, confirm\u00f3 que present\u00f3 un pedido de informes al Consejo Escolar luego de las denuncias difundidas en redes sociales sobre presuntas irregularidades en alimentos entregados en establecimientos educativos del distrito. En Cosas que pasan, explic\u00f3 que la iniciativa surgi\u00f3 a partir de la preocupaci\u00f3n manifestada por familias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":58338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-65123","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Piden informaci\u00f3n por el estado de alimentos escolares y cuestionan la situaci\u00f3n de Reta - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piden informaci\u00f3n por el estado de alimentos escolares y cuestionan la situaci\u00f3n de Reta - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"La concejal de la Coalici\u00f3n C\u00edvica, Cecilia del Aguila, confirm\u00f3 que present\u00f3 un pedido de informes al Consejo Escolar luego de las denuncias difundidas en redes sociales sobre presuntas irregularidades en alimentos entregados en establecimientos educativos del distrito. En Cosas que pasan, explic\u00f3 que la iniciativa surgi\u00f3 a partir de la preocupaci\u00f3n manifestada por familias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-02T22:51:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T22:51:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-11-at-14.09.58.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1204\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/\",\"name\":\"Piden informaci\u00f3n por el estado de alimentos escolares y cuestionan la situaci\u00f3n de Reta - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-11-at-14.09.58.jpeg\",\"datePublished\":\"2026-06-02T22:51:18+00:00\",\"dateModified\":\"2026-06-02T22:51:24+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-11-at-14.09.58.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-11-at-14.09.58.jpeg\",\"width\":1600,\"height\":1204},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piden informaci\u00f3n por el estado de alimentos escolares y cuestionan la situaci\u00f3n de Reta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piden informaci\u00f3n por el estado de alimentos escolares y cuestionan la situaci\u00f3n de Reta - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/","og_locale":"es_ES","og_type":"article","og_title":"Piden informaci\u00f3n por el estado de alimentos escolares y cuestionan la situaci\u00f3n de Reta - 103.9 fm","og_description":"La concejal de la Coalici\u00f3n C\u00edvica, Cecilia del Aguila, confirm\u00f3 que present\u00f3 un pedido de informes al Consejo Escolar luego de las denuncias difundidas en redes sociales sobre presuntas irregularidades en alimentos entregados en establecimientos educativos del distrito. En Cosas que pasan, explic\u00f3 que la iniciativa surgi\u00f3 a partir de la preocupaci\u00f3n manifestada por familias [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2026-06-02T22:51:18+00:00","article_modified_time":"2026-06-02T22:51:24+00:00","og_image":[{"width":1600,"height":1204,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-11-at-14.09.58.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/","url":"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/","name":"Piden informaci\u00f3n por el estado de alimentos escolares y cuestionan la situaci\u00f3n de Reta - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-11-at-14.09.58.jpeg","datePublished":"2026-06-02T22:51:18+00:00","dateModified":"2026-06-02T22:51:24+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-11-at-14.09.58.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-11-at-14.09.58.jpeg","width":1600,"height":1204},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/06\/02\/piden-informacion-por-el-estado-de-alimentos-escolares-y-cuestionan-la-situacion-de-reta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Piden informaci\u00f3n por el estado de alimentos escolares y cuestionan la situaci\u00f3n de Reta"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-11-at-14.09.58.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=65123"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65123\/revisions"}],"predecessor-version":[{"id":65124,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65123\/revisions\/65124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/58338"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=65123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=65123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=65123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}