{"id":63287,"date":"2026-02-25T18:11:52","date_gmt":"2026-02-25T21:11:52","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=63287"},"modified":"2026-02-25T18:11:55","modified_gmt":"2026-02-25T21:11:55","slug":"se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/","title":{"rendered":"Se mejora la plazoleta frente a Seguridad y se suma una pista vial para chicos"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-3703799983\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>La Municipalidad de Tres Arroyos dejar\u00e1 inaugurada ma\u00f1ana jueves 26 a las 18:00hs la puesta en valor de la plazoleta ubicada frente a la Secretar\u00eda de Seguridad sobre la calle Castelli, una obra que incluye un embellecimiento integral del espacio.<\/p>\n\n\n\n<p>Los trabajos contemplan la instalaci\u00f3n de nuevas luminarias, la reparaci\u00f3n y restauraci\u00f3n de los juegos existentes y tareas de parquizaci\u00f3n, con el objetivo de mejorar el lugar y hacerlo m\u00e1s seguro y disfrutable para toda la familia.<br>Adem\u00e1s, se incorpora una pista vial destinada a los m\u00e1s chicos, pensada como un espacio educativo donde puedan aprender, de manera did\u00e1ctica, las normas b\u00e1sicas de tr\u00e1nsito y la importancia del respeto por las reglas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-1024x576.jpeg\" alt=\"\" class=\"wp-image-63289 lazyload\" data-srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-1024x576.jpeg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-300x169.jpeg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-768x432.jpeg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-1536x864.jpeg 1536w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-747x420.jpeg 747w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-696x391.jpeg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-1068x600.jpeg 1068w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04.jpeg 1599w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-1024x576.jpeg\" alt=\"\" class=\"wp-image-63289\" srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-1024x576.jpeg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-300x169.jpeg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-768x432.jpeg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-1536x864.jpeg 1536w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-747x420.jpeg 747w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-696x391.jpeg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04-1068x600.jpeg 1068w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.04.jpeg 1599w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<p>La educaci\u00f3n y la concientizaci\u00f3n vial son ejes centrales de esta gesti\u00f3n. Esta iniciativa apunta a formar desde temprana edad una cultura de responsabilidad y convivencia en la v\u00eda p\u00fablica.<\/p>\n\n\n\n<p>La obra fue realizada por diferentes sectores de la Municipalidad, principalmente por la cuadrilla de Acci\u00f3n Social, en un trabajo conjunto que permiti\u00f3 concretar esta mejora para la vida de los vecinos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-1024x576.jpeg\" alt=\"\" class=\"wp-image-63290 lazyload\" data-srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-1024x576.jpeg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-300x169.jpeg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-768x432.jpeg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-1536x864.jpeg 1536w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-747x420.jpeg 747w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-696x391.jpeg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-1068x600.jpeg 1068w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23.jpeg 1599w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-1024x576.jpeg\" alt=\"\" class=\"wp-image-63290\" srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-1024x576.jpeg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-300x169.jpeg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-768x432.jpeg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-1536x864.jpeg 1536w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-747x420.jpeg 747w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-696x391.jpeg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23-1068x600.jpeg 1068w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.28.23.jpeg 1599w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Tres Arroyos dejar\u00e1 inaugurada ma\u00f1ana jueves 26 a las 18:00hs la puesta en valor de la plazoleta ubicada frente a la Secretar\u00eda de Seguridad sobre la calle Castelli, una obra que incluye un embellecimiento integral del espacio. Los trabajos contemplan la instalaci\u00f3n de nuevas luminarias, la reparaci\u00f3n y restauraci\u00f3n de los juegos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":63288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-63287","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se mejora la plazoleta frente a Seguridad y se suma una pista vial para chicos - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se mejora la plazoleta frente a Seguridad y se suma una pista vial para chicos - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"La Municipalidad de Tres Arroyos dejar\u00e1 inaugurada ma\u00f1ana jueves 26 a las 18:00hs la puesta en valor de la plazoleta ubicada frente a la Secretar\u00eda de Seguridad sobre la calle Castelli, una obra que incluye un embellecimiento integral del espacio. Los trabajos contemplan la instalaci\u00f3n de nuevas luminarias, la reparaci\u00f3n y restauraci\u00f3n de los juegos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-25T21:11:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T21:11:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.05.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/\",\"name\":\"Se mejora la plazoleta frente a Seguridad y se suma una pista vial para chicos - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.05.jpeg\",\"datePublished\":\"2026-02-25T21:11:52+00:00\",\"dateModified\":\"2026-02-25T21:11:55+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.05.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.05.jpeg\",\"width\":1599,\"height\":899},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se mejora la plazoleta frente a Seguridad y se suma una pista vial para chicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se mejora la plazoleta frente a Seguridad y se suma una pista vial para chicos - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/","og_locale":"es_ES","og_type":"article","og_title":"Se mejora la plazoleta frente a Seguridad y se suma una pista vial para chicos - 103.9 fm","og_description":"La Municipalidad de Tres Arroyos dejar\u00e1 inaugurada ma\u00f1ana jueves 26 a las 18:00hs la puesta en valor de la plazoleta ubicada frente a la Secretar\u00eda de Seguridad sobre la calle Castelli, una obra que incluye un embellecimiento integral del espacio. Los trabajos contemplan la instalaci\u00f3n de nuevas luminarias, la reparaci\u00f3n y restauraci\u00f3n de los juegos [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2026-02-25T21:11:52+00:00","article_modified_time":"2026-02-25T21:11:55+00:00","og_image":[{"width":1599,"height":899,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.05.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/","url":"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/","name":"Se mejora la plazoleta frente a Seguridad y se suma una pista vial para chicos - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.05.jpeg","datePublished":"2026-02-25T21:11:52+00:00","dateModified":"2026-02-25T21:11:55+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.05.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.05.jpeg","width":1599,"height":899},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/02\/25\/se-mejora-la-plazoleta-frente-a-seguridad-y-se-suma-una-pista-vial-para-chicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Se mejora la plazoleta frente a Seguridad y se suma una pista vial para chicos"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-15.29.05.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/63287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=63287"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/63287\/revisions"}],"predecessor-version":[{"id":63291,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/63287\/revisions\/63291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/63288"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=63287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=63287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=63287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}