{"id":62578,"date":"2026-01-15T02:43:53","date_gmt":"2026-01-15T05:43:53","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=62578"},"modified":"2026-01-15T02:43:57","modified_gmt":"2026-01-15T05:43:57","slug":"gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/","title":{"rendered":"Gripe A: refuerzan la vacunaci\u00f3n y la telemedicina en Tres Arroyos"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-1905851704\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>La secretaria municipal de Salud del distrito de Tres Arroyos, Mercedes Moreno, se refiri\u00f3 al reciente caso confirmado de gripe A y llev\u00f3 tranquilidad a la comunidad, al aclarar que se trata de \u201cla misma gripe que circula todos los a\u00f1os\u201d y que no se han detectado cuadros graves ni circulaci\u00f3n comunitaria en la ciudad.<\/p>\n\n\n\n<p>En Cosas que pasan, Moreno explic\u00f3 que el caso corresponde a una persona que tuvo contacto con viajeros provenientes del continente europeo y que present\u00f3 s\u00edntomas leves, sin necesidad de internaci\u00f3n. \u201cNo hemos detectado circulaci\u00f3n porque no se registr\u00f3 un aumento de casos de s\u00edndrome gripal\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>La funcionaria indic\u00f3 que el subtipo detectado, Influenza A H3, ha sido m\u00e1s contagioso en Europa y Estados Unidos, pero aclar\u00f3 que \u201cno ha demostrado formas graves de la enfermedad\u201d. En ese sentido, remarc\u00f3 la importancia de la prevenci\u00f3n: \u201cLa herramienta fundamental sigue siendo la vacunaci\u00f3n, sobre todo para los grupos de riesgo\u201d.<\/p>\n\n\n\n<p>Moreno record\u00f3 que las personas con factores de riesgo que no se hayan vacunado en 2025 a\u00fan pueden hacerlo durante enero. Entre los grupos priorizados se encuentran embarazadas, ni\u00f1os menores de dos a\u00f1os, mayores de 65 a\u00f1os y personas menores de esa edad con enfermedades preexistentes. \u201cDespu\u00e9s de enero se espera la llegada de la vacuna correspondiente a la campa\u00f1a 2026\u201d, explic\u00f3.<\/p>\n\n\n\n<p>Desde el Centro Municipal de Salud tambi\u00e9n se activaron protocolos internos ante la posibilidad de un aumento de consultas durante el oto\u00f1o e invierno. \u201cYa trabajamos con los jefes de servicio, guardias y terapia intensiva, y contamos con provisi\u00f3n de medicaci\u00f3n e insumos necesarios\u201d, afirm\u00f3 la secretaria de Salud.<\/p>\n\n\n\n<p>Adem\u00e1s Moreno destac\u00f3 el funcionamiento del sistema de telemedicina, disponible las 24 horas para todos los vecinos del distrito. \u201cEs ideal para consultas por s\u00edntomas leves, como los respiratorios, porque permite una primera evaluaci\u00f3n m\u00e9dica sin salir de casa y sin riesgo de contagiar a otras personas\u201d, explic\u00f3. El servicio se puede utilizar a trav\u00e9s de la aplicaci\u00f3n MiTresa o desde la p\u00e1gina del Centro Municipal de Salud.<\/p>\n\n\n\n<p>En ese marco tambi\u00e9n resalt\u00f3 la instalaci\u00f3n de t\u00f3tems de telemedicina en el Hospital Pirovano y en Claromec\u00f3, destinados a orientar a quienes se acerquen con consultas que no revistan gravedad.<\/p>\n\n\n\n<p>Por \u00faltimo Moreno record\u00f3 que ya est\u00e1 en marcha la campa\u00f1a de vacunaci\u00f3n contra el Virus Sincicial Respiratorio, destinada a mujeres embarazadas entre las semanas 32 y 36 de gestaci\u00f3n, con el objetivo de prevenir cuadros graves de bronquiolitis en reci\u00e9n nacidos.<\/p>\n\n\n\n<p>Pod\u00e9s escuchar la nota completa en el siguiente link:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"ZEtdJ1dkqfk\"><iframe loading=\"lazy\" title=\"Onda Uno 103.9 en vivo\" width=\"696\" height=\"392\" data-src=\"https:\/\/www.youtube.com\/embed\/ZEtdJ1dkqfk?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La secretaria municipal de Salud del distrito de Tres Arroyos, Mercedes Moreno, se refiri\u00f3 al reciente caso confirmado de gripe A y llev\u00f3 tranquilidad a la comunidad, al aclarar que se trata de \u201cla misma gripe que circula todos los a\u00f1os\u201d y que no se han detectado cuadros graves ni circulaci\u00f3n comunitaria en la ciudad. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-62578","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gripe A: refuerzan la vacunaci\u00f3n y la telemedicina en Tres Arroyos - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gripe A: refuerzan la vacunaci\u00f3n y la telemedicina en Tres Arroyos - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"La secretaria municipal de Salud del distrito de Tres Arroyos, Mercedes Moreno, se refiri\u00f3 al reciente caso confirmado de gripe A y llev\u00f3 tranquilidad a la comunidad, al aclarar que se trata de \u201cla misma gripe que circula todos los a\u00f1os\u201d y que no se han detectado cuadros graves ni circulaci\u00f3n comunitaria en la ciudad. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-15T05:43:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T05:43:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/07\/mercedes-moreno-onda-uno.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/\",\"name\":\"Gripe A: refuerzan la vacunaci\u00f3n y la telemedicina en Tres Arroyos - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/07\/mercedes-moreno-onda-uno.jpeg\",\"datePublished\":\"2026-01-15T05:43:53+00:00\",\"dateModified\":\"2026-01-15T05:43:57+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/07\/mercedes-moreno-onda-uno.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/07\/mercedes-moreno-onda-uno.jpeg\",\"width\":880,\"height\":493},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gripe A: refuerzan la vacunaci\u00f3n y la telemedicina en Tres Arroyos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gripe A: refuerzan la vacunaci\u00f3n y la telemedicina en Tres Arroyos - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/","og_locale":"es_ES","og_type":"article","og_title":"Gripe A: refuerzan la vacunaci\u00f3n y la telemedicina en Tres Arroyos - 103.9 fm","og_description":"La secretaria municipal de Salud del distrito de Tres Arroyos, Mercedes Moreno, se refiri\u00f3 al reciente caso confirmado de gripe A y llev\u00f3 tranquilidad a la comunidad, al aclarar que se trata de \u201cla misma gripe que circula todos los a\u00f1os\u201d y que no se han detectado cuadros graves ni circulaci\u00f3n comunitaria en la ciudad. [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2026-01-15T05:43:53+00:00","article_modified_time":"2026-01-15T05:43:57+00:00","og_image":[{"width":880,"height":493,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/07\/mercedes-moreno-onda-uno.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/","url":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/","name":"Gripe A: refuerzan la vacunaci\u00f3n y la telemedicina en Tres Arroyos - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/07\/mercedes-moreno-onda-uno.jpeg","datePublished":"2026-01-15T05:43:53+00:00","dateModified":"2026-01-15T05:43:57+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/07\/mercedes-moreno-onda-uno.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/07\/mercedes-moreno-onda-uno.jpeg","width":880,"height":493},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/15\/gripe-a-refuerzan-la-vacunacion-y-la-telemedicina-en-tres-arroyos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Gripe A: refuerzan la vacunaci\u00f3n y la telemedicina en Tres Arroyos"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/07\/mercedes-moreno-onda-uno.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/62578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=62578"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/62578\/revisions"}],"predecessor-version":[{"id":62579,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/62578\/revisions\/62579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/12901"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=62578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=62578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=62578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}