{"id":62523,"date":"2026-01-12T20:11:35","date_gmt":"2026-01-12T23:11:35","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=62523"},"modified":"2026-01-12T20:11:41","modified_gmt":"2026-01-12T23:11:41","slug":"la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/","title":{"rendered":"La Escuela de Emprendedores rumbo al 2026, trabajo conjunto con el \u00e1rea de Discapacidad"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-361550788\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>El \u00c1rea de Discapacidad y la Escuela de Emprendedores, una propuesta con gran proyecci\u00f3n impulsada por la Direcci\u00f3n de Emprendedurismo de la Municipalidad de Tres Arroyos, iniciaron un proceso de planificaci\u00f3n conjunta con vistas al a\u00f1o 2026.<\/p>\n\n\n\n<p>En este marco se lanzar\u00e1 un relevamiento abierto a todo p\u00fablico y totalmente gratuito, destinado a conocer las necesidades, intereses y expectativas de la comunidad. El objetivo es construir una propuesta de actividades y capacitaciones ajustadas a la realidad local, potenciando especialmente el acceso y la participaci\u00f3n de personas con discapacidad y sus familias.<br>La planificaci\u00f3n contempla la siguiente oferta formativa:<\/p>\n\n\n\n<p>Organizaci\u00f3n de la idea\u2013proyecto<\/p>\n\n\n\n<p>Crecimiento y expansi\u00f3n<\/p>\n\n\n\n<p>Comunicaci\u00f3n para impulsar el emprendimiento<\/p>\n\n\n\n<p>Reglamentaci\u00f3n del emprendimiento<\/p>\n\n\n\n<p>Costos y precios<\/p>\n\n\n\n<p>Servicios de traslado y log\u00edstica<\/p>\n\n\n\n<p>Todas las actividades de la Escuela de Emprendedores son gratuitas, abiertas a la comunidad y orientadas a fortalecer proyectos accesibles, sostenibles e inclusivos.<br>Adem\u00e1s, quienes participen del ciclo completo de capacitaciones recibir\u00e1n una certificaci\u00f3n que acredite el trayecto formativo. Por lo cual se invita a la comunidad a completar una breve encuesta en el siguiente: https:\/\/forms.gle\/XJZPuYfw7Ug9DjK57<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u00c1rea de Discapacidad y la Escuela de Emprendedores, una propuesta con gran proyecci\u00f3n impulsada por la Direcci\u00f3n de Emprendedurismo de la Municipalidad de Tres Arroyos, iniciaron un proceso de planificaci\u00f3n conjunta con vistas al a\u00f1o 2026. En este marco se lanzar\u00e1 un relevamiento abierto a todo p\u00fablico y totalmente gratuito, destinado a conocer las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":62524,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-62523","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Escuela de Emprendedores rumbo al 2026, trabajo conjunto con el \u00e1rea de Discapacidad - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Escuela de Emprendedores rumbo al 2026, trabajo conjunto con el \u00e1rea de Discapacidad - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"El \u00c1rea de Discapacidad y la Escuela de Emprendedores, una propuesta con gran proyecci\u00f3n impulsada por la Direcci\u00f3n de Emprendedurismo de la Municipalidad de Tres Arroyos, iniciaron un proceso de planificaci\u00f3n conjunta con vistas al a\u00f1o 2026. En este marco se lanzar\u00e1 un relevamiento abierto a todo p\u00fablico y totalmente gratuito, destinado a conocer las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-12T23:11:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T23:11:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-12-at-14.01.59.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/\",\"name\":\"La Escuela de Emprendedores rumbo al 2026, trabajo conjunto con el \u00e1rea de Discapacidad - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-12-at-14.01.59.jpeg\",\"datePublished\":\"2026-01-12T23:11:35+00:00\",\"dateModified\":\"2026-01-12T23:11:41+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-12-at-14.01.59.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-12-at-14.01.59.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Escuela de Emprendedores rumbo al 2026, trabajo conjunto con el \u00e1rea de Discapacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Escuela de Emprendedores rumbo al 2026, trabajo conjunto con el \u00e1rea de Discapacidad - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/","og_locale":"es_ES","og_type":"article","og_title":"La Escuela de Emprendedores rumbo al 2026, trabajo conjunto con el \u00e1rea de Discapacidad - 103.9 fm","og_description":"El \u00c1rea de Discapacidad y la Escuela de Emprendedores, una propuesta con gran proyecci\u00f3n impulsada por la Direcci\u00f3n de Emprendedurismo de la Municipalidad de Tres Arroyos, iniciaron un proceso de planificaci\u00f3n conjunta con vistas al a\u00f1o 2026. En este marco se lanzar\u00e1 un relevamiento abierto a todo p\u00fablico y totalmente gratuito, destinado a conocer las [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2026-01-12T23:11:35+00:00","article_modified_time":"2026-01-12T23:11:41+00:00","og_image":[{"width":1280,"height":960,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-12-at-14.01.59.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/","url":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/","name":"La Escuela de Emprendedores rumbo al 2026, trabajo conjunto con el \u00e1rea de Discapacidad - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-12-at-14.01.59.jpeg","datePublished":"2026-01-12T23:11:35+00:00","dateModified":"2026-01-12T23:11:41+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-12-at-14.01.59.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-12-at-14.01.59.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2026\/01\/12\/la-escuela-de-emprendedores-rumbo-al-2026-trabajo-conjunto-con-el-area-de-discapacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"La Escuela de Emprendedores rumbo al 2026, trabajo conjunto con el \u00e1rea de Discapacidad"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-12-at-14.01.59.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/62523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=62523"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/62523\/revisions"}],"predecessor-version":[{"id":62525,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/62523\/revisions\/62525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/62524"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=62523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=62523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=62523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}