{"id":61078,"date":"2025-10-14T21:55:26","date_gmt":"2025-10-15T00:55:26","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=61078"},"modified":"2025-10-14T21:55:30","modified_gmt":"2025-10-15T00:55:30","slug":"nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/","title":{"rendered":"Nuevo encuentro para pacientes oncol\u00f3gicos y de enfermedades cr\u00f3nicas desde el servicio de oncolog\u00eda del CMS"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-3386626977\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>Ma\u00f1ana mi\u00e9rcoles 15 de octubre, de 16:30 a 18:00 hs, se llevar\u00e1 a cabo un nuevo encuentro para Pacientes Oncol\u00f3gicos y con Enfermedades Cr\u00f3nicas en el Museo Mulazzi (Av. San Mart\u00edn 323).<\/p>\n\n\n\n<p>La propuesta invita a compartir una tarde de contenci\u00f3n, di\u00e1logo y aprendizaje junto al equipo de Oncolog\u00eda del Centro Municipal de Salud. Durante la jornada habr\u00e1 merienda, actividades grupales e intercambio de experiencias para pacientes y familiares.<\/p>\n\n\n\n<p>La participaci\u00f3n es gratuita y no requiere inscripci\u00f3n previa.<\/p>\n\n\n\n<p>\u00a1Los esperamos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma\u00f1ana mi\u00e9rcoles 15 de octubre, de 16:30 a 18:00 hs, se llevar\u00e1 a cabo un nuevo encuentro para Pacientes Oncol\u00f3gicos y con Enfermedades Cr\u00f3nicas en el Museo Mulazzi (Av. San Mart\u00edn 323). La propuesta invita a compartir una tarde de contenci\u00f3n, di\u00e1logo y aprendizaje junto al equipo de Oncolog\u00eda del Centro Municipal de Salud. Durante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-61078","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nuevo encuentro para pacientes oncol\u00f3gicos y de enfermedades cr\u00f3nicas desde el servicio de oncolog\u00eda del CMS - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevo encuentro para pacientes oncol\u00f3gicos y de enfermedades cr\u00f3nicas desde el servicio de oncolog\u00eda del CMS - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"Ma\u00f1ana mi\u00e9rcoles 15 de octubre, de 16:30 a 18:00 hs, se llevar\u00e1 a cabo un nuevo encuentro para Pacientes Oncol\u00f3gicos y con Enfermedades Cr\u00f3nicas en el Museo Mulazzi (Av. San Mart\u00edn 323). La propuesta invita a compartir una tarde de contenci\u00f3n, di\u00e1logo y aprendizaje junto al equipo de Oncolog\u00eda del Centro Municipal de Salud. Durante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T00:55:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T00:55:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-13.24.32.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/\",\"name\":\"Nuevo encuentro para pacientes oncol\u00f3gicos y de enfermedades cr\u00f3nicas desde el servicio de oncolog\u00eda del CMS - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-13.24.32.jpeg\",\"datePublished\":\"2025-10-15T00:55:26+00:00\",\"dateModified\":\"2025-10-15T00:55:30+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-13.24.32.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-13.24.32.jpeg\",\"width\":1131,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevo encuentro para pacientes oncol\u00f3gicos y de enfermedades cr\u00f3nicas desde el servicio de oncolog\u00eda del CMS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevo encuentro para pacientes oncol\u00f3gicos y de enfermedades cr\u00f3nicas desde el servicio de oncolog\u00eda del CMS - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevo encuentro para pacientes oncol\u00f3gicos y de enfermedades cr\u00f3nicas desde el servicio de oncolog\u00eda del CMS - 103.9 fm","og_description":"Ma\u00f1ana mi\u00e9rcoles 15 de octubre, de 16:30 a 18:00 hs, se llevar\u00e1 a cabo un nuevo encuentro para Pacientes Oncol\u00f3gicos y con Enfermedades Cr\u00f3nicas en el Museo Mulazzi (Av. San Mart\u00edn 323). La propuesta invita a compartir una tarde de contenci\u00f3n, di\u00e1logo y aprendizaje junto al equipo de Oncolog\u00eda del Centro Municipal de Salud. Durante [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2025-10-15T00:55:26+00:00","article_modified_time":"2025-10-15T00:55:30+00:00","og_image":[{"width":1131,"height":1600,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-13.24.32.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/","url":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/","name":"Nuevo encuentro para pacientes oncol\u00f3gicos y de enfermedades cr\u00f3nicas desde el servicio de oncolog\u00eda del CMS - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-13.24.32.jpeg","datePublished":"2025-10-15T00:55:26+00:00","dateModified":"2025-10-15T00:55:30+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-13.24.32.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-13.24.32.jpeg","width":1131,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/nuevo-encuentro-para-pacientes-oncologicos-y-de-enfermedades-cronicas-desde-el-servicio-de-oncologia-del-cms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Nuevo encuentro para pacientes oncol\u00f3gicos y de enfermedades cr\u00f3nicas desde el servicio de oncolog\u00eda del CMS"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-13.24.32.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/61078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=61078"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/61078\/revisions"}],"predecessor-version":[{"id":61080,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/61078\/revisions\/61080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/61079"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=61078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=61078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=61078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}