{"id":61061,"date":"2025-10-14T13:28:55","date_gmt":"2025-10-14T16:28:55","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=61061"},"modified":"2025-10-14T13:29:00","modified_gmt":"2025-10-14T16:29:00","slug":"buscan-a-un-hombre-desaparecido-en-tres-arroyos","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/","title":{"rendered":"Buscan a un hombre desaparecido en Tres Arroyos"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-2306180657\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>La Polic\u00eda de Tres Arroyos solicita la colaboraci\u00f3n de la comunidad para dar con el paradero de Lucas Samuel Ibarra, de 35 a\u00f1os, quien se encuentra desaparecido desde el lunes 13 de octubre de 2025, cuando fue visto por \u00faltima vez alrededor de las 14 horas en su domicilio de calle Alsina 58 de esta ciudad.<\/p>\n\n\n\n<p>Ibarra es de tez blanca, mide aproximadamente 1,70 metros, tiene ojos marrones y cabello casta\u00f1o oscuro corto. Como se\u00f1a particular, posee un tatuaje con un c\u00f3digo de barras en el pecho. Al momento de ausentarse vest\u00eda pantal\u00f3n de jean azul oscuro, buzo beige con estampas fucsia y zapatillas Adidas blancas.<\/p>\n\n\n\n<p>Se inform\u00f3 adem\u00e1s que su cuenta de Instagram es @samuelibarra445 y su tel\u00e9fono celular es 2235-775978.<\/p>\n\n\n\n<p>La denuncia fue radicada por su tutora Alejandra Daiana Arista, quien autoriz\u00f3 la difusi\u00f3n de fotograf\u00edas en los medios de comunicaci\u00f3n.<\/p>\n\n\n\n<p>Ante cualquier informaci\u00f3n sobre su paradero, se solicita comunicarse al 911, al 147, o acercarse a la dependencia policial m\u00e1s cercana.<\/p>\n\n\n\n<p>La investigaci\u00f3n est\u00e1 a cargo de la Unidad Funcional de Instrucci\u00f3n y Juicio N\u00b0 16, del Departamento Judicial Bah\u00eda Blanca \u2013 sede Tres Arroyos, bajo la intervenci\u00f3n del Fiscal Dr. Gabriel Iv\u00e1n Lopazzo, en el marco de la causa caratulada \u201cAveriguaci\u00f3n de Paradero\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda de Tres Arroyos solicita la colaboraci\u00f3n de la comunidad para dar con el paradero de Lucas Samuel Ibarra, de 35 a\u00f1os, quien se encuentra desaparecido desde el lunes 13 de octubre de 2025, cuando fue visto por \u00faltima vez alrededor de las 14 horas en su domicilio de calle Alsina 58 de esta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-61061","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Buscan a un hombre desaparecido en Tres Arroyos - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buscan a un hombre desaparecido en Tres Arroyos - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"La Polic\u00eda de Tres Arroyos solicita la colaboraci\u00f3n de la comunidad para dar con el paradero de Lucas Samuel Ibarra, de 35 a\u00f1os, quien se encuentra desaparecido desde el lunes 13 de octubre de 2025, cuando fue visto por \u00faltima vez alrededor de las 14 horas en su domicilio de calle Alsina 58 de esta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-14T16:28:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T16:29:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-00.25.10.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/\",\"name\":\"Buscan a un hombre desaparecido en Tres Arroyos - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-00.25.10.jpeg\",\"datePublished\":\"2025-10-14T16:28:55+00:00\",\"dateModified\":\"2025-10-14T16:29:00+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-00.25.10.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-00.25.10.jpeg\",\"width\":900,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buscan a un hombre desaparecido en Tres Arroyos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buscan a un hombre desaparecido en Tres Arroyos - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/","og_locale":"es_ES","og_type":"article","og_title":"Buscan a un hombre desaparecido en Tres Arroyos - 103.9 fm","og_description":"La Polic\u00eda de Tres Arroyos solicita la colaboraci\u00f3n de la comunidad para dar con el paradero de Lucas Samuel Ibarra, de 35 a\u00f1os, quien se encuentra desaparecido desde el lunes 13 de octubre de 2025, cuando fue visto por \u00faltima vez alrededor de las 14 horas en su domicilio de calle Alsina 58 de esta [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2025-10-14T16:28:55+00:00","article_modified_time":"2025-10-14T16:29:00+00:00","og_image":[{"width":900,"height":1600,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-00.25.10.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/","url":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/","name":"Buscan a un hombre desaparecido en Tres Arroyos - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-00.25.10.jpeg","datePublished":"2025-10-14T16:28:55+00:00","dateModified":"2025-10-14T16:29:00+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-00.25.10.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-00.25.10.jpeg","width":900,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/10\/14\/buscan-a-un-hombre-desaparecido-en-tres-arroyos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Buscan a un hombre desaparecido en Tres Arroyos"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-00.25.10.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/61061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=61061"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/61061\/revisions"}],"predecessor-version":[{"id":61063,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/61061\/revisions\/61063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/61062"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=61061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=61061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=61061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}