{"id":54636,"date":"2025-03-26T20:19:27","date_gmt":"2025-03-26T23:19:27","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=54636"},"modified":"2025-03-26T20:19:29","modified_gmt":"2025-03-26T23:19:29","slug":"vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/","title":{"rendered":"&#8220;Vacunas: peque\u00f1as dosis de vida&#8221;; por la doctora Florencia Fosque"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-3686374936\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>En Cosas que pasan, la pediatra Florencia Fosque inform\u00f3 sobre la campa\u00f1a de vacunaci\u00f3n en marcha y destac\u00f3 la importancia de la inmunizaci\u00f3n para prevenir enfermedades.<\/p>\n\n\n\n<p>&#8220;Es fundamental que la poblaci\u00f3n acceda a las vacunas disponibles, ya que representan una herramienta clave para la salud p\u00fablica&#8221;, se\u00f1al\u00f3 Fosque.<\/p>\n\n\n\n<p>Asimismo explic\u00f3 que los centros de salud cuentan con stock suficiente y que &#8220;no es necesario sacar turno previo, solo hay que acercarse en los horarios establecidos&#8221;. Tambi\u00e9n resalt\u00f3 la seguridad de las vacunas, desmintiendo informaciones falsas: &#8220;Todas las dosis han sido aprobadas y son seguras para su aplicaci\u00f3n&#8221;.<\/p>\n\n\n\n<p>Finalmente record\u00f3 la importancia de mantener el calendario de vacunaci\u00f3n al d\u00eda y recomend\u00f3 a la comunidad informarse a trav\u00e9s de fuentes oficiales.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"Y06VfOV0P9k\"><iframe loading=\"lazy\" title=\"Onda Uno 103.9 en vivo\" width=\"696\" height=\"392\" data-src=\"https:\/\/www.youtube.com\/embed\/Y06VfOV0P9k?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En Cosas que pasan, la pediatra Florencia Fosque inform\u00f3 sobre la campa\u00f1a de vacunaci\u00f3n en marcha y destac\u00f3 la importancia de la inmunizaci\u00f3n para prevenir enfermedades. &#8220;Es fundamental que la poblaci\u00f3n acceda a las vacunas disponibles, ya que representan una herramienta clave para la salud p\u00fablica&#8221;, se\u00f1al\u00f3 Fosque. Asimismo explic\u00f3 que los centros de salud [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":{"0":"post-54636","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-interes-general"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Vacunas: peque\u00f1as dosis de vida&quot;; por la doctora Florencia Fosque - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Vacunas: peque\u00f1as dosis de vida&quot;; por la doctora Florencia Fosque - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"En Cosas que pasan, la pediatra Florencia Fosque inform\u00f3 sobre la campa\u00f1a de vacunaci\u00f3n en marcha y destac\u00f3 la importancia de la inmunizaci\u00f3n para prevenir enfermedades. &#8220;Es fundamental que la poblaci\u00f3n acceda a las vacunas disponibles, ya que representan una herramienta clave para la salud p\u00fablica&#8221;, se\u00f1al\u00f3 Fosque. Asimismo explic\u00f3 que los centros de salud [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-26T23:19:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-26T23:19:29+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-26-at-19.11.21.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/\",\"name\":\"\\\"Vacunas: peque\u00f1as dosis de vida\\\"; por la doctora Florencia Fosque - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-26-at-19.11.21.jpeg\",\"datePublished\":\"2025-03-26T23:19:27+00:00\",\"dateModified\":\"2025-03-26T23:19:29+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-26-at-19.11.21.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-26-at-19.11.21.jpeg\",\"width\":1152,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Vacunas: peque\u00f1as dosis de vida&#8221;; por la doctora Florencia Fosque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Vacunas: peque\u00f1as dosis de vida\"; por la doctora Florencia Fosque - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/","og_locale":"es_ES","og_type":"article","og_title":"\"Vacunas: peque\u00f1as dosis de vida\"; por la doctora Florencia Fosque - 103.9 fm","og_description":"En Cosas que pasan, la pediatra Florencia Fosque inform\u00f3 sobre la campa\u00f1a de vacunaci\u00f3n en marcha y destac\u00f3 la importancia de la inmunizaci\u00f3n para prevenir enfermedades. &#8220;Es fundamental que la poblaci\u00f3n acceda a las vacunas disponibles, ya que representan una herramienta clave para la salud p\u00fablica&#8221;, se\u00f1al\u00f3 Fosque. Asimismo explic\u00f3 que los centros de salud [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2025-03-26T23:19:27+00:00","article_modified_time":"2025-03-26T23:19:29+00:00","og_image":[{"width":1152,"height":1600,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-26-at-19.11.21.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/","url":"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/","name":"\"Vacunas: peque\u00f1as dosis de vida\"; por la doctora Florencia Fosque - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-26-at-19.11.21.jpeg","datePublished":"2025-03-26T23:19:27+00:00","dateModified":"2025-03-26T23:19:29+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-26-at-19.11.21.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-26-at-19.11.21.jpeg","width":1152,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2025\/03\/26\/vacunas-pequenas-dosis-de-vida-por-la-doctora-florencia-fosque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"&#8220;Vacunas: peque\u00f1as dosis de vida&#8221;; por la doctora Florencia Fosque"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-26-at-19.11.21.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/54636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=54636"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/54636\/revisions"}],"predecessor-version":[{"id":54638,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/54636\/revisions\/54638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/54637"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=54636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=54636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=54636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}