{"id":52027,"date":"2024-11-26T22:47:13","date_gmt":"2024-11-27T01:47:13","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=52027"},"modified":"2024-11-26T22:47:16","modified_gmt":"2024-11-27T01:47:16","slug":"garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/","title":{"rendered":"Garate habl\u00f3 de su agenda: desde Malter\u00eda y Telef\u00f3nica hasta la temporada de verano"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-2680969125\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>El intendente de Tres Arroyos, Pablo Garate, habl\u00f3 en &#8220;Cosas que pasan&#8221;, donde coment\u00f3 sobre diversos proyectos y gestiones que est\u00e1 llevando a cabo en la ciudad y el distrito. Desde Buenos Aires, Garate detall\u00f3 su reuni\u00f3n con representantes de la empresa Malter\u00eda Quilmes, en la que se trata la articulaci\u00f3n p\u00fablico-privada para fomentar el desarrollo local.<\/p>\n\n\n\n<p>En relaci\u00f3n al Centro Regional de Estudios Superiores, Garate explic\u00f3 que las gestiones con Telef\u00f3nica contin\u00faan, tras la falta de documentaci\u00f3n que dej\u00f3 la gesti\u00f3n anterior. &#8220;Estamos trabajando con Telef\u00f3nica para resolver la situaci\u00f3n del edificio, y esperamos que antes de fin de a\u00f1o podamos tener una resoluci\u00f3n positiva&#8221;, afirm\u00f3.<\/p>\n\n\n\n<p>Sobre la concesi\u00f3n de la arenera de Claromec\u00f3, el intendente destac\u00f3 que se ha trabajado para ordenar la situaci\u00f3n y evitar el da\u00f1o ambiental que gener\u00f3 la falta de control en gestiones pasadas. &#8220;Estamos trabajando para que se cumpla lo que dice la licitaci\u00f3n y que los recursos generados por la arenera beneficien a los vecinos de Claromec\u00f3&#8221;, expres\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s Garate anunci\u00f3 avances en el plan de iluminaci\u00f3n LED en diferentes localidades del distrito, con un recambio de luminarias en Claromec\u00f3, Orense y otras localidades, lo que traer\u00e1 mayor seguridad y ahorro energ\u00e9tico.<\/p>\n\n\n\n<p>En cuanto a la temporada de verano, el intendente destac\u00f3 las mejoras en los caminos de acceso a los balnearios y los trabajos en el balneario de Cascallares. &#8220;Estamos trabajando para tener todo listo para la temporada, con mejor infraestructura y m\u00e1s seguridad para los vecinos y turistas&#8221;, asegur\u00f3.<\/p>\n\n\n\n<p>Finalmente el intendente tresarroyense coment\u00f3 sobre los avances en la seguridad en las playas y el apoyo a los prestadores tur\u00edsticos para una temporada exitosa. &#8220;Estamos trabajando junto a los privados para que todo est\u00e9 en \u00f3ptimas condiciones&#8221;, concluy\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"rQt8U4H6XUk\"><iframe loading=\"lazy\" title=\"Onda Uno 103.9 en vivo\" width=\"696\" height=\"392\" data-src=\"https:\/\/www.youtube.com\/embed\/rQt8U4H6XUk?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de Tres Arroyos, Pablo Garate, habl\u00f3 en &#8220;Cosas que pasan&#8221;, donde coment\u00f3 sobre diversos proyectos y gestiones que est\u00e1 llevando a cabo en la ciudad y el distrito. Desde Buenos Aires, Garate detall\u00f3 su reuni\u00f3n con representantes de la empresa Malter\u00eda Quilmes, en la que se trata la articulaci\u00f3n p\u00fablico-privada para fomentar el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":51693,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-52027","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Garate habl\u00f3 de su agenda: desde Malter\u00eda y Telef\u00f3nica hasta la temporada de verano - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garate habl\u00f3 de su agenda: desde Malter\u00eda y Telef\u00f3nica hasta la temporada de verano - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"El intendente de Tres Arroyos, Pablo Garate, habl\u00f3 en &#8220;Cosas que pasan&#8221;, donde coment\u00f3 sobre diversos proyectos y gestiones que est\u00e1 llevando a cabo en la ciudad y el distrito. Desde Buenos Aires, Garate detall\u00f3 su reuni\u00f3n con representantes de la empresa Malter\u00eda Quilmes, en la que se trata la articulaci\u00f3n p\u00fablico-privada para fomentar el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-27T01:47:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T01:47:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/11\/pablo-garate.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1204\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/\",\"name\":\"Garate habl\u00f3 de su agenda: desde Malter\u00eda y Telef\u00f3nica hasta la temporada de verano - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/11\/pablo-garate.jpeg\",\"datePublished\":\"2024-11-27T01:47:13+00:00\",\"dateModified\":\"2024-11-27T01:47:16+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/11\/pablo-garate.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/11\/pablo-garate.jpeg\",\"width\":1600,\"height\":1204},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garate habl\u00f3 de su agenda: desde Malter\u00eda y Telef\u00f3nica hasta la temporada de verano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garate habl\u00f3 de su agenda: desde Malter\u00eda y Telef\u00f3nica hasta la temporada de verano - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/","og_locale":"es_ES","og_type":"article","og_title":"Garate habl\u00f3 de su agenda: desde Malter\u00eda y Telef\u00f3nica hasta la temporada de verano - 103.9 fm","og_description":"El intendente de Tres Arroyos, Pablo Garate, habl\u00f3 en &#8220;Cosas que pasan&#8221;, donde coment\u00f3 sobre diversos proyectos y gestiones que est\u00e1 llevando a cabo en la ciudad y el distrito. Desde Buenos Aires, Garate detall\u00f3 su reuni\u00f3n con representantes de la empresa Malter\u00eda Quilmes, en la que se trata la articulaci\u00f3n p\u00fablico-privada para fomentar el [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2024-11-27T01:47:13+00:00","article_modified_time":"2024-11-27T01:47:16+00:00","og_image":[{"width":1600,"height":1204,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/11\/pablo-garate.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/","url":"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/","name":"Garate habl\u00f3 de su agenda: desde Malter\u00eda y Telef\u00f3nica hasta la temporada de verano - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/11\/pablo-garate.jpeg","datePublished":"2024-11-27T01:47:13+00:00","dateModified":"2024-11-27T01:47:16+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/11\/pablo-garate.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/11\/pablo-garate.jpeg","width":1600,"height":1204},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/11\/26\/garate-hablo-de-su-agenda-desde-malteria-y-telefonica-hasta-la-temporada-de-verano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Garate habl\u00f3 de su agenda: desde Malter\u00eda y Telef\u00f3nica hasta la temporada de verano"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/11\/pablo-garate.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=52027"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52027\/revisions"}],"predecessor-version":[{"id":52028,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52027\/revisions\/52028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/51693"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=52027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=52027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=52027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}