{"id":50797,"date":"2024-10-03T22:20:17","date_gmt":"2024-10-04T01:20:17","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=50797"},"modified":"2024-10-03T22:20:20","modified_gmt":"2024-10-04T01:20:20","slug":"subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/","title":{"rendered":"Subasta de arte local a beneficio de la Escuela Secundaria Especializada en Arte"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-2113628027\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p class=\"has-small-font-size\"><strong><em>Algunas de las obras que ser\u00e1n subastadas este viernes en La Estaci\u00f3n<\/em><\/strong><\/p>\n\n\n\n<p>Este viernes 4 de octubre, a las 19:30, en la sala de exposiciones del Centro Cultural Estaci\u00f3n, se llevar\u00e1 a cabo una subasta de obras de arte realizadas por artistas locales, con el objetivo de recaudar fondos para la compra de materiales destinados a la escuela ESEA. La licenciada en artes pl\u00e1sticas Victoria De Francesco, en Cosas que pasan brind\u00f3 detalles sobre el evento.<\/p>\n\n\n\n<p>\u201cEste proyecto lo trabajamos con los alumnos de la escuela y lo recaudado ser\u00e1 para la compra de materiales y para colaborar con la cooperadora\u201d, explic\u00f3 De Francesco.<\/p>\n\n\n\n<p>La subasta cuenta con la participaci\u00f3n de artistas y comercios de la comunidad.<\/p>\n\n\n\n<p>\u201cLa idea fue que distintos actores, como alumnos, profesores y artistas locales, participen en conjunto. Adem\u00e1s el martillero Gonzalo Ferro nos va a acompa\u00f1ar\u201d, agreg\u00f3 la licenciada.<\/p>\n\n\n\n<p>El evento ser\u00e1 una oportunidad para colaborar y adquirir obras de artistas locales.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"qTp3IivfGnM\"><iframe loading=\"lazy\" title=\"Onda Uno 103.9 en vivo\" width=\"696\" height=\"392\" data-src=\"https:\/\/www.youtube.com\/embed\/qTp3IivfGnM?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Algunas de las obras que ser\u00e1n subastadas este viernes en La Estaci\u00f3n Este viernes 4 de octubre, a las 19:30, en la sala de exposiciones del Centro Cultural Estaci\u00f3n, se llevar\u00e1 a cabo una subasta de obras de arte realizadas por artistas locales, con el objetivo de recaudar fondos para la compra de materiales destinados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-50797","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Subasta de arte local a beneficio de la Escuela Secundaria Especializada en Arte - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subasta de arte local a beneficio de la Escuela Secundaria Especializada en Arte - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"Algunas de las obras que ser\u00e1n subastadas este viernes en La Estaci\u00f3n Este viernes 4 de octubre, a las 19:30, en la sala de exposiciones del Centro Cultural Estaci\u00f3n, se llevar\u00e1 a cabo una subasta de obras de arte realizadas por artistas locales, con el objetivo de recaudar fondos para la compra de materiales destinados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-04T01:20:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-04T01:20:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/10\/obras-1024x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/\",\"name\":\"Subasta de arte local a beneficio de la Escuela Secundaria Especializada en Arte - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/10\/obras.png\",\"datePublished\":\"2024-10-04T01:20:17+00:00\",\"dateModified\":\"2024-10-04T01:20:20+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/10\/obras.png\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/10\/obras.png\",\"width\":1999,\"height\":1999},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Subasta de arte local a beneficio de la Escuela Secundaria Especializada en Arte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subasta de arte local a beneficio de la Escuela Secundaria Especializada en Arte - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/","og_locale":"es_ES","og_type":"article","og_title":"Subasta de arte local a beneficio de la Escuela Secundaria Especializada en Arte - 103.9 fm","og_description":"Algunas de las obras que ser\u00e1n subastadas este viernes en La Estaci\u00f3n Este viernes 4 de octubre, a las 19:30, en la sala de exposiciones del Centro Cultural Estaci\u00f3n, se llevar\u00e1 a cabo una subasta de obras de arte realizadas por artistas locales, con el objetivo de recaudar fondos para la compra de materiales destinados [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2024-10-04T01:20:17+00:00","article_modified_time":"2024-10-04T01:20:20+00:00","og_image":[{"width":1024,"height":1024,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/10\/obras-1024x1024.png","type":"image\/png"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/","url":"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/","name":"Subasta de arte local a beneficio de la Escuela Secundaria Especializada en Arte - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/10\/obras.png","datePublished":"2024-10-04T01:20:17+00:00","dateModified":"2024-10-04T01:20:20+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/10\/obras.png","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/10\/obras.png","width":1999,"height":1999},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/10\/03\/subasta-de-arte-local-a-beneficio-de-la-escuela-secundaria-especializada-en-arte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Subasta de arte local a beneficio de la Escuela Secundaria Especializada en Arte"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/10\/obras.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/50797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=50797"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/50797\/revisions"}],"predecessor-version":[{"id":50799,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/50797\/revisions\/50799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/50798"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=50797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=50797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=50797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}