{"id":47955,"date":"2024-06-18T11:46:13","date_gmt":"2024-06-18T14:46:13","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=47955"},"modified":"2024-06-18T11:46:15","modified_gmt":"2024-06-18T14:46:15","slug":"evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/","title":{"rendered":"Evoluci\u00f3n y desaf\u00edos el ex Colegio Nacional, a 95 de su nacimiento"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-208566389\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p class=\"has-small-font-size\"><strong><em>Equipo completo de secundaria Vicedirectores de cada turno y secretarios<\/em><\/strong><\/p>\n\n\n\n<p>En Cosas que pasan, Claudia Palmas, directora de la Escuela Secundaria N\u00b02, conocida como el ex Colegio Nacional, comparti\u00f3 su experiencia y visi\u00f3n sobre la instituci\u00f3n educativa y los desaf\u00edos actuales que enfrenta.<\/p>\n\n\n\n<p>Asumi\u00f3 la direcci\u00f3n en octubre del a\u00f1o pasado, tiene una larga trayectoria en el Colegio Nacional. Fue alumna en los a\u00f1os 90, regres\u00f3 como docente en el 2000 y se desempe\u00f1\u00f3 como vicedirectora desde 2018.<br>Con el retiro de Valeria Tapia, Palmas asumi\u00f3 la direcci\u00f3n de la escuela, que celebra su 95\u00ba aniversario este a\u00f1o.<br>Durante la entrevista, Palmas destac\u00f3 varios desaf\u00edos que enfrenta la educaci\u00f3n secundaria hoy en d\u00eda. Uno de los problemas m\u00e1s significativos es el ausentismo y la deserci\u00f3n escolar, fen\u00f3menos que han aumentado con el tiempo.<br>La falta de asistencia regular se debe a varios factores, incluyendo la necesidad de muchos estudiantes de trabajar y la falta de apoyo familiar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"461\" height=\"1024\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.07-2-461x1024.jpeg\" alt=\"\" class=\"wp-image-47959 lazyload\" data-srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.07-2-461x1024.jpeg 461w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.07-2-135x300.jpeg 135w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.07-2-189x420.jpeg 189w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.07-2.jpeg 576w\" data-sizes=\"auto, (max-width: 461px) 100vw, 461px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 461px; --smush-placeholder-aspect-ratio: 461\/1024;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"461\" height=\"1024\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.07-2-461x1024.jpeg\" alt=\"\" class=\"wp-image-47959\" srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.07-2-461x1024.jpeg 461w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.07-2-135x300.jpeg 135w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.07-2-189x420.jpeg 189w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.07-2.jpeg 576w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/noscript><figcaption class=\"wp-element-caption\">Junto a su profesora de secundar\u00eda Cristina Ponizio<\/figcaption><\/figure>\n\n\n\n<p>Adem\u00e1s Palmas mencion\u00f3 el papel crucial del equipo de orientaci\u00f3n escolar en la atenci\u00f3n de cuestiones emocionales de los estudiantes, algo que no era tan com\u00fan en su \u00e9poca de estudiante. La directora tambi\u00e9n subray\u00f3 el impacto de la tecnolog\u00eda en la vida estudiantil, destacando que, aunque es una herramienta valiosa, su uso excesivo puede ser perjudicial.<\/p>\n\n\n\n<p>La celebraci\u00f3n del 95\u00ba aniversario del colegio cont\u00f3 con la presencia de exalumnos destacados como el intendente Pablo Garate y el secretario de Hacienda Sergio Garcimunio.<br>Palmas destac\u00f3 la emotividad del evento y la importancia de mantener la participaci\u00f3n estudiantil y la cultura democr\u00e1tica dentro de la instituci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-gestor-del-servicio wp-block-embed-gestor-del-servicio wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"fpsuy-BnbG0\"><iframe loading=\"lazy\" title=\"Onda Uno 103.9 en vivo\" width=\"696\" height=\"392\" data-src=\"https:\/\/www.youtube.com\/embed\/fpsuy-BnbG0?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Equipo completo de secundaria Vicedirectores de cada turno y secretarios En Cosas que pasan, Claudia Palmas, directora de la Escuela Secundaria N\u00b02, conocida como el ex Colegio Nacional, comparti\u00f3 su experiencia y visi\u00f3n sobre la instituci\u00f3n educativa y los desaf\u00edos actuales que enfrenta. Asumi\u00f3 la direcci\u00f3n en octubre del a\u00f1o pasado, tiene una larga trayectoria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":47957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-47955","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Evoluci\u00f3n y desaf\u00edos el ex Colegio Nacional, a 95 de su nacimiento - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evoluci\u00f3n y desaf\u00edos el ex Colegio Nacional, a 95 de su nacimiento - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"Equipo completo de secundaria Vicedirectores de cada turno y secretarios En Cosas que pasan, Claudia Palmas, directora de la Escuela Secundaria N\u00b02, conocida como el ex Colegio Nacional, comparti\u00f3 su experiencia y visi\u00f3n sobre la instituci\u00f3n educativa y los desaf\u00edos actuales que enfrenta. Asumi\u00f3 la direcci\u00f3n en octubre del a\u00f1o pasado, tiene una larga trayectoria [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-18T14:46:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-18T14:46:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.08.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"963\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/\",\"name\":\"Evoluci\u00f3n y desaf\u00edos el ex Colegio Nacional, a 95 de su nacimiento - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.08.jpeg\",\"datePublished\":\"2024-06-18T14:46:13+00:00\",\"dateModified\":\"2024-06-18T14:46:15+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.08.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.08.jpeg\",\"width\":1280,\"height\":963},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evoluci\u00f3n y desaf\u00edos el ex Colegio Nacional, a 95 de su nacimiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evoluci\u00f3n y desaf\u00edos el ex Colegio Nacional, a 95 de su nacimiento - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Evoluci\u00f3n y desaf\u00edos el ex Colegio Nacional, a 95 de su nacimiento - 103.9 fm","og_description":"Equipo completo de secundaria Vicedirectores de cada turno y secretarios En Cosas que pasan, Claudia Palmas, directora de la Escuela Secundaria N\u00b02, conocida como el ex Colegio Nacional, comparti\u00f3 su experiencia y visi\u00f3n sobre la instituci\u00f3n educativa y los desaf\u00edos actuales que enfrenta. Asumi\u00f3 la direcci\u00f3n en octubre del a\u00f1o pasado, tiene una larga trayectoria [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2024-06-18T14:46:13+00:00","article_modified_time":"2024-06-18T14:46:15+00:00","og_image":[{"width":1280,"height":963,"url":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.08.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/","url":"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/","name":"Evoluci\u00f3n y desaf\u00edos el ex Colegio Nacional, a 95 de su nacimiento - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.08.jpeg","datePublished":"2024-06-18T14:46:13+00:00","dateModified":"2024-06-18T14:46:15+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.08.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.08.jpeg","width":1280,"height":963},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2024\/06\/18\/evolucion-y-desafios-el-ex-colegio-nacional-a-95-de-su-nacimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Evoluci\u00f3n y desaf\u00edos el ex Colegio Nacional, a 95 de su nacimiento"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-18-at-11.12.08.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=47955"}],"version-history":[{"count":1,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47955\/revisions"}],"predecessor-version":[{"id":47960,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47955\/revisions\/47960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/47957"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=47955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=47955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=47955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}