{"id":43234,"date":"2023-08-17T18:35:45","date_gmt":"2023-08-17T21:35:45","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=43234"},"modified":"2023-08-17T18:35:46","modified_gmt":"2023-08-17T21:35:46","slug":"concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/","title":{"rendered":"Concejo: Plantean acciones para mejorar la gesti\u00f3n de residuos en Reta"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-2316710579\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>El titular de Gesti\u00f3n Ambiental municipal, Ricardo D\u2019 Annunzio; Oscar Chan, funcionario de esa cartera y Santiago Treffenberg, vecino de Balneario Reta que recientemente plante\u00f3 problem\u00e1ticas vinculadas a la gesti\u00f3n de residuos en esa localidad, participaron este jueves de la reuni\u00f3n de la Comisi\u00f3n de Acci\u00f3n Social y Medio Ambiente del Concejo, donde en principio los primeros dieron a conocer algunas acciones relacionadas con la tem\u00e1tica que tienen previsto desplegar en breve en el lugar. <\/p>\n\n\n\n<p>Treffenberg hab\u00eda puesto de manifiesto, en una reciente sesi\u00f3n del Legislativo, la presencia de basura domiciliaria en un espacio a cielo abierto destinado a residuos de poda y voluminosos, por lo que se acord\u00f3 con los funcionarios que se ordenar\u00e1 y sanear\u00e1 ese sitio, al tiempo que se buscar\u00e1 instalar un Punto Verde donde concentrar la disposici\u00f3n de residuos que no forman parte del esquema de recolecci\u00f3n. Este \u00faltimo, consideraron, se podr\u00eda instalar entre Reta y Copetonas para gestionar ese tipo de desechos de manera regionalizada. <\/p>\n\n\n\n<p>D\u2019 Annunzio anticip\u00f3 adem\u00e1s que se est\u00e1 proyectando la instalaci\u00f3n, en el trazado urbano de Reta, de estaciones ambientales que incluyan un basur\u00edn comunitario para la disposici\u00f3n de reciclables y una compostera para los desechos org\u00e1nicos. Mientras que Chan inform\u00f3 que se gestiona financiamiento para la radicaci\u00f3n de una estaci\u00f3n sustentable para su uso en temporada alta, que buscar\u00e1 ofrecer a los turistas un espacio de disposici\u00f3n de residuos para evitar su proliferaci\u00f3n en la playa. <\/p>\n\n\n\n<p>Facundo Elgart (Todos), presidente de la Comisi\u00f3n, lament\u00f3 que no haya estado presente el delegado en Reta, Lucas Oviedo, \u201cmuy importante para esta reuni\u00f3n, porque son varias las \u00e1reas que hay que articular en este tema. En lo inmediato se acord\u00f3 el saneamiento de la cava donde se tiraron dos camiones de basura domiciliaria, y la instalaci\u00f3n de una casilla en ese lugar para controlar que no se arrojen residuos urbanos. Mientras que se buscar\u00e1 otro punto para trabajar los desechos de escombros, ramas, para planificar adecuadamente esa tarea. Esperemos llegar a buen puerto con esto, y trabajar en puntos de reciclado, diez en la localidad, que ya empezar\u00edan a instalar el primero en estas semanas\u201d. <\/p>\n\n\n\n<p><br>En tanto, el concejal Cristian Ruiz (Juntos), vicepresidente de la Comisi\u00f3n, consider\u00f3 que \u201cfue un encuentro productivo, porque se trataron temas relacionados con la gesti\u00f3n de residuos y hubo propuestas, tanto del vecino que us\u00f3 la Banca Ciudadana como del propio Concejo y de los funcionarios, para que se controle la basura que se recibe en ese espacio a cielo abierto y que los residuos domiciliarios lleguen a la Planta en Tres Arroyos, generando una articulaci\u00f3n entre la Delegaci\u00f3n y Gesti\u00f3n Ambiental, que es algo que hoy est\u00e1 fallando y hay que mejorar\u201d.<\/p>\n\n\n\n<p><br> \u201cEsta es una problem\u00e1tica que est\u00e1 creciendo, de hecho el vecino hizo una denuncia federal, que ya lleg\u00f3 el oficio a la Secretar\u00eda. Por eso, hay que tener en cuenta que Reta ha crecido mucho y eso dificulta los recorridos para la recolecci\u00f3n, que Malvinas hace en 74 manzanas pero hay un mont\u00f3n m\u00e1s, que hace la Delegaci\u00f3n y a veces van a parar al basural a cielo abierto. Y tambi\u00e9n hay que resolver el tema de los desechos cloacales, porque quien brindaba ese servicio hoy est\u00e1 trabajando en Copetonas, y en temporada alta eso va a ser un inconveniente. Por eso es fundamental articular y tener una pol\u00edtica clara de cuidado del medio ambiente\u201d, complet\u00f3 Ruiz. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El titular de Gesti\u00f3n Ambiental municipal, Ricardo D\u2019 Annunzio; Oscar Chan, funcionario de esa cartera y Santiago Treffenberg, vecino de Balneario Reta que recientemente plante\u00f3 problem\u00e1ticas vinculadas a la gesti\u00f3n de residuos en esa localidad, participaron este jueves de la reuni\u00f3n de la Comisi\u00f3n de Acci\u00f3n Social y Medio Ambiente del Concejo, donde en principio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-43234","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Concejo: Plantean acciones para mejorar la gesti\u00f3n de residuos en Reta - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concejo: Plantean acciones para mejorar la gesti\u00f3n de residuos en Reta - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"El titular de Gesti\u00f3n Ambiental municipal, Ricardo D\u2019 Annunzio; Oscar Chan, funcionario de esa cartera y Santiago Treffenberg, vecino de Balneario Reta que recientemente plante\u00f3 problem\u00e1ticas vinculadas a la gesti\u00f3n de residuos en esa localidad, participaron este jueves de la reuni\u00f3n de la Comisi\u00f3n de Acci\u00f3n Social y Medio Ambiente del Concejo, donde en principio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-17T21:35:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-17T21:35:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-17-at-14.35.03.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/\",\"name\":\"Concejo: Plantean acciones para mejorar la gesti\u00f3n de residuos en Reta - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"datePublished\":\"2023-08-17T21:35:45+00:00\",\"dateModified\":\"2023-08-17T21:35:46+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concejo: Plantean acciones para mejorar la gesti\u00f3n de residuos en Reta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concejo: Plantean acciones para mejorar la gesti\u00f3n de residuos en Reta - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/","og_locale":"es_ES","og_type":"article","og_title":"Concejo: Plantean acciones para mejorar la gesti\u00f3n de residuos en Reta - 103.9 fm","og_description":"El titular de Gesti\u00f3n Ambiental municipal, Ricardo D\u2019 Annunzio; Oscar Chan, funcionario de esa cartera y Santiago Treffenberg, vecino de Balneario Reta que recientemente plante\u00f3 problem\u00e1ticas vinculadas a la gesti\u00f3n de residuos en esa localidad, participaron este jueves de la reuni\u00f3n de la Comisi\u00f3n de Acci\u00f3n Social y Medio Ambiente del Concejo, donde en principio [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2023-08-17T21:35:45+00:00","article_modified_time":"2023-08-17T21:35:46+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-17-at-14.35.03.jpeg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/","url":"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/","name":"Concejo: Plantean acciones para mejorar la gesti\u00f3n de residuos en Reta - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"datePublished":"2023-08-17T21:35:45+00:00","dateModified":"2023-08-17T21:35:46+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2023\/08\/17\/concejo-plantean-acciones-para-mejorar-la-gestion-de-residuos-en-reta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Concejo: Plantean acciones para mejorar la gesti\u00f3n de residuos en Reta"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/43234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=43234"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/43234\/revisions"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=43234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=43234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=43234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}