{"id":35774,"date":"2022-09-04T13:31:15","date_gmt":"2022-09-04T16:31:15","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=35774"},"modified":"2022-09-04T13:31:16","modified_gmt":"2022-09-04T16:31:16","slug":"villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/","title":{"rendered":"Villa del Parque: habl\u00f3 Vacca tras el fallo del Consejo Federal"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-3439929667\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>El presidente del club tresarroyense se expres\u00f3 en Cosas que pasan despu\u00e9s que en una instancia superior al Tribunal de Disciplina de la Liga Regional Tresarroyense de F\u00fatbol, se absolviera a la instituci\u00f3n y a uno de sus trabajadores, por una denuncia por intento de soborno.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"161\" data-src=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-1024x161.jpg\" alt=\"\" class=\"wp-image-32072 lazyload\" data-srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-1024x161.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-300x47.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-768x121.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-696x110.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-1068x168.jpg 1068w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-1920x302.jpg 1920w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/161;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"161\" src=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-1024x161.jpg\" alt=\"\" class=\"wp-image-32072\" srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-1024x161.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-300x47.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-768x121.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-696x110.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-1068x168.jpg 1068w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/03\/Escucha-la-nota1-1920x302.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<figure><iframe loading=\"lazy\" data-src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fwww.facebook.com%2Fondauno103.9%2Fvideos%2F346720930916014%2F&amp;show_text=false&amp;width=560&amp;t=0\" width=\"560\" height=\"314\" allowfullscreen=\"true\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del club tresarroyense se expres\u00f3 en Cosas que pasan despu\u00e9s que en una instancia superior al Tribunal de Disciplina de la Liga Regional Tresarroyense de F\u00fatbol, se absolviera a la instituci\u00f3n y a uno de sus trabajadores, por una denuncia por intento de soborno.<\/p>\n","protected":false},"author":1,"featured_media":35372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-35774","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Villa del Parque: habl\u00f3 Vacca tras el fallo del Consejo Federal - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa del Parque: habl\u00f3 Vacca tras el fallo del Consejo Federal - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"El presidente del club tresarroyense se expres\u00f3 en Cosas que pasan despu\u00e9s que en una instancia superior al Tribunal de Disciplina de la Liga Regional Tresarroyense de F\u00fatbol, se absolviera a la instituci\u00f3n y a uno de sus trabajadores, por una denuncia por intento de soborno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-04T16:31:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-04T16:31:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/08\/Vacca-Quintana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"748\" \/>\n\t<meta property=\"og:image:height\" content=\"616\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OndaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"OndaUno\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/\",\"name\":\"Villa del Parque: habl\u00f3 Vacca tras el fallo del Consejo Federal - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/08\/Vacca-Quintana.jpg\",\"datePublished\":\"2022-09-04T16:31:15+00:00\",\"dateModified\":\"2022-09-04T16:31:16+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/08\/Vacca-Quintana.jpg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/08\/Vacca-Quintana.jpg\",\"width\":748,\"height\":616},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villa del Parque: habl\u00f3 Vacca tras el fallo del Consejo Federal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e\",\"name\":\"OndaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g\",\"caption\":\"OndaUno\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa del Parque: habl\u00f3 Vacca tras el fallo del Consejo Federal - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/","og_locale":"es_ES","og_type":"article","og_title":"Villa del Parque: habl\u00f3 Vacca tras el fallo del Consejo Federal - 103.9 fm","og_description":"El presidente del club tresarroyense se expres\u00f3 en Cosas que pasan despu\u00e9s que en una instancia superior al Tribunal de Disciplina de la Liga Regional Tresarroyense de F\u00fatbol, se absolviera a la instituci\u00f3n y a uno de sus trabajadores, por una denuncia por intento de soborno.","og_url":"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2022-09-04T16:31:15+00:00","article_modified_time":"2022-09-04T16:31:16+00:00","og_image":[{"width":748,"height":616,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/08\/Vacca-Quintana.jpg","type":"image\/jpeg"}],"author":"OndaUno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"OndaUno"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/","url":"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/","name":"Villa del Parque: habl\u00f3 Vacca tras el fallo del Consejo Federal - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/08\/Vacca-Quintana.jpg","datePublished":"2022-09-04T16:31:15+00:00","dateModified":"2022-09-04T16:31:16+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/08\/Vacca-Quintana.jpg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/08\/Vacca-Quintana.jpg","width":748,"height":616},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2022\/09\/04\/villa-del-parque-hablo-vacca-tras-el-fallo-del-consejo-federal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Villa del Parque: habl\u00f3 Vacca tras el fallo del Consejo Federal"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/7ec851ddeceb4133d7d7132dc645714e","name":"OndaUno","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93b8009f0de7021f1feb2bd5b32fb9e8?s=96&d=mm&r=g","caption":"OndaUno"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondauno\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2022\/08\/Vacca-Quintana.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/35774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=35774"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/35774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/35372"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=35774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=35774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=35774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}