{"id":31035,"date":"2021-12-21T10:48:28","date_gmt":"2021-12-21T13:48:28","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=31035"},"modified":"2021-12-22T12:57:39","modified_gmt":"2021-12-22T15:57:39","slug":"presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/","title":{"rendered":"Presupuesto: el Concejo analiza una propuesta alternativa priorizando  el control del gasto para evitar el &#8220;tasazo&#8221; del 55%"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-1264872485\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p class=\"has-small-font-size\"><em>Soledad Cadenas en Cosas que pasan<\/em><\/p>\n\n\n\n<p>La concejal del Frente de Todos, Soledad Cadenas, cont\u00f3 en Cosas que pasan c\u00f3mo se intenta llegar a un acuerdo con el oficialismo, con una contrapropuesta que evite el tasazo del 55 por ciento que pidi\u00f3 el intendente Carlos S\u00e1nchez.<\/p>\n\n\n\n<figure><iframe loading=\"lazy\" data-src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fwww.facebook.com%2Fondauno103.9%2Fvideos%2F4514994591951738%2F&amp;show_text=false&amp;width=560&amp;t=0\" width=\"560\" height=\"314\" allowfullscreen=\"true\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Soledad Cadenas en Cosas que pasan La concejal del Frente de Todos, Soledad Cadenas, cont\u00f3 en Cosas que pasan c\u00f3mo se intenta llegar a un acuerdo con el oficialismo, con una contrapropuesta que evite el tasazo del 55 por ciento que pidi\u00f3 el intendente Carlos S\u00e1nchez.<\/p>\n","protected":false},"author":2,"featured_media":31036,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-31035","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presupuesto: el Concejo analiza una propuesta alternativa priorizando el control del gasto para evitar el &quot;tasazo&quot; del 55% - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presupuesto: el Concejo analiza una propuesta alternativa priorizando el control del gasto para evitar el &quot;tasazo&quot; del 55% - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"Soledad Cadenas en Cosas que pasan La concejal del Frente de Todos, Soledad Cadenas, cont\u00f3 en Cosas que pasan c\u00f3mo se intenta llegar a un acuerdo con el oficialismo, con una contrapropuesta que evite el tasazo del 55 por ciento que pidi\u00f3 el intendente Carlos S\u00e1nchez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-21T13:48:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-22T15:57:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/12\/Soledad-Cadenas.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1547\" \/>\n\t<meta property=\"og:image:height\" content=\"1291\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/\",\"name\":\"Presupuesto: el Concejo analiza una propuesta alternativa priorizando el control del gasto para evitar el \\\"tasazo\\\" del 55% - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/12\/Soledad-Cadenas.jpeg\",\"datePublished\":\"2021-12-21T13:48:28+00:00\",\"dateModified\":\"2021-12-22T15:57:39+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/12\/Soledad-Cadenas.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/12\/Soledad-Cadenas.jpeg\",\"width\":1547,\"height\":1291},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presupuesto: el Concejo analiza una propuesta alternativa priorizando el control del gasto para evitar el &#8220;tasazo&#8221; del 55%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presupuesto: el Concejo analiza una propuesta alternativa priorizando el control del gasto para evitar el \"tasazo\" del 55% - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/","og_locale":"es_ES","og_type":"article","og_title":"Presupuesto: el Concejo analiza una propuesta alternativa priorizando el control del gasto para evitar el \"tasazo\" del 55% - 103.9 fm","og_description":"Soledad Cadenas en Cosas que pasan La concejal del Frente de Todos, Soledad Cadenas, cont\u00f3 en Cosas que pasan c\u00f3mo se intenta llegar a un acuerdo con el oficialismo, con una contrapropuesta que evite el tasazo del 55 por ciento que pidi\u00f3 el intendente Carlos S\u00e1nchez.","og_url":"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2021-12-21T13:48:28+00:00","article_modified_time":"2021-12-22T15:57:39+00:00","og_image":[{"width":1547,"height":1291,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/12\/Soledad-Cadenas.jpeg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/","url":"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/","name":"Presupuesto: el Concejo analiza una propuesta alternativa priorizando el control del gasto para evitar el \"tasazo\" del 55% - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/12\/Soledad-Cadenas.jpeg","datePublished":"2021-12-21T13:48:28+00:00","dateModified":"2021-12-22T15:57:39+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/12\/Soledad-Cadenas.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/12\/Soledad-Cadenas.jpeg","width":1547,"height":1291},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/12\/21\/presupuesto-el-concejo-analiza-una-propuesta-alternativa-priorizando-el-control-del-gasto-para-evitar-el-tasazo-del-58\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Presupuesto: el Concejo analiza una propuesta alternativa priorizando el control del gasto para evitar el &#8220;tasazo&#8221; del 55%"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/12\/Soledad-Cadenas.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=31035"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/31036"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=31035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=31035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=31035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}