{"id":30262,"date":"2021-11-15T08:42:38","date_gmt":"2021-11-15T11:42:38","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=30262"},"modified":"2021-11-15T08:42:39","modified_gmt":"2021-11-15T11:42:39","slug":"el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/","title":{"rendered":"El Frente de Todos, Con Pity Federico, logr\u00f3 tres concejales y es la segunda fuerza local"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-3392015128\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>El peronismo kirchnerista tresarroyense, con Julio Pity Federico como cabeza de lista, logr\u00f3 una buena elecci\u00f3n en las elecciones legislativas de este domingo 14 de noviembre.<\/p>\n\n\n\n<p>Con el 29,15 por ciento de los votos que representan a 10.076 electores, se consolid\u00f3 como segunda fuerza pol\u00edtica del distrito, por el sobre el vecinalismo que sum\u00f3 menos que en las PASO, llegando al 23,33 por ciento de los votos, equivalentes a 8.063 electores.<\/p>\n\n\n\n<p>Pero especialmente la segunda posici\u00f3n del Frente de Todos tiene m\u00e1s m\u00e9rito en Tres Arroyos, distrito donde los gobiernos bonaerense y nacional han demostrado apoyar m\u00e1s la gesti\u00f3n de un municipio vecinalista, que el trabajo de sus propios representantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El peronismo kirchnerista tresarroyense, con Julio Pity Federico como cabeza de lista, logr\u00f3 una buena elecci\u00f3n en las elecciones legislativas de este domingo 14 de noviembre. Con el 29,15 por ciento de los votos que representan a 10.076 electores, se consolid\u00f3 como segunda fuerza pol\u00edtica del distrito, por el sobre el vecinalismo que sum\u00f3 menos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-30262","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Frente de Todos, Con Pity Federico, logr\u00f3 tres concejales y es la segunda fuerza local - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Frente de Todos, Con Pity Federico, logr\u00f3 tres concejales y es la segunda fuerza local - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"El peronismo kirchnerista tresarroyense, con Julio Pity Federico como cabeza de lista, logr\u00f3 una buena elecci\u00f3n en las elecciones legislativas de este domingo 14 de noviembre. Con el 29,15 por ciento de los votos que representan a 10.076 electores, se consolid\u00f3 como segunda fuerza pol\u00edtica del distrito, por el sobre el vecinalismo que sum\u00f3 menos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-15T11:42:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-15T11:42:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/11\/frente-de-todos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3012\" \/>\n\t<meta property=\"og:image:height\" content=\"1392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/\",\"name\":\"El Frente de Todos, Con Pity Federico, logr\u00f3 tres concejales y es la segunda fuerza local - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"datePublished\":\"2021-11-15T11:42:38+00:00\",\"dateModified\":\"2021-11-15T11:42:39+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Frente de Todos, Con Pity Federico, logr\u00f3 tres concejales y es la segunda fuerza local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Frente de Todos, Con Pity Federico, logr\u00f3 tres concejales y es la segunda fuerza local - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/","og_locale":"es_ES","og_type":"article","og_title":"El Frente de Todos, Con Pity Federico, logr\u00f3 tres concejales y es la segunda fuerza local - 103.9 fm","og_description":"El peronismo kirchnerista tresarroyense, con Julio Pity Federico como cabeza de lista, logr\u00f3 una buena elecci\u00f3n en las elecciones legislativas de este domingo 14 de noviembre. Con el 29,15 por ciento de los votos que representan a 10.076 electores, se consolid\u00f3 como segunda fuerza pol\u00edtica del distrito, por el sobre el vecinalismo que sum\u00f3 menos [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2021-11-15T11:42:38+00:00","article_modified_time":"2021-11-15T11:42:39+00:00","og_image":[{"width":3012,"height":1392,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/11\/frente-de-todos.jpg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/","url":"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/","name":"El Frente de Todos, Con Pity Federico, logr\u00f3 tres concejales y es la segunda fuerza local - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"datePublished":"2021-11-15T11:42:38+00:00","dateModified":"2021-11-15T11:42:39+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/11\/15\/el-frente-de-todos-con-pity-federico-logro-tres-concejales-y-es-la-segunda-fuerza-local\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"El Frente de Todos, Con Pity Federico, logr\u00f3 tres concejales y es la segunda fuerza local"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/30262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=30262"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/30262\/revisions"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=30262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=30262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=30262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}