{"id":28218,"date":"2021-08-31T22:45:25","date_gmt":"2021-09-01T01:45:25","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=28218"},"modified":"2021-08-31T22:45:26","modified_gmt":"2021-09-01T01:45:26","slug":"paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/","title":{"rendered":"Paulatinamente comienza a aplicarse la presencialidad plena en Tres Arroyos"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-1589502262\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>Este martes, a primera hora, la inspectora jefe distrital, Andrea Larrieu Lacoste inform\u00f3 a Cosas que pasan que transcurr\u00eda su \u00faltima jornada de trabajo, despu\u00e9s que se confirmara oficialmente su jubilaci\u00f3n.<\/p>\n\n\n\n<p>En este contexto se dio a conocer que el proceso del regreso a la presencialidad se dar\u00e1 de acuerdo a la situaci\u00f3n de cada establecimiento, y en el marco de lo que establece el gobierno nacional.<\/p>\n\n\n\n<p>En Tres Arroyos, Educaci\u00f3n dispone de la normativa con la actualizaci\u00f3n del Plan Jurisdiccional, y las escuelas van a poder iniciar este tan esperado proceso, seg\u00fan el plan de prevenci\u00f3n de riesgo.<\/p>\n\n\n\n<p>Cada establecimiento educativo deber\u00e1 organizarse en base a la normativa, cuesti\u00f3n que ser\u00e1 supervisada, previamente, por los inspectores del plan.<\/p>\n\n\n\n<p>Es por eso que no todos los establecimientos comenzar\u00e1n las clases presenciales completas desde este mi\u00e9rcoles 1 de septiembre.<\/p>\n\n\n\n<p>Ese paso se dar\u00e1 gradualmente, de acuerdo al plan establecido.<\/p>\n\n\n\n<p>Ello considera que la distancia social dentro de las aulas pasar\u00e1 de 1,5 mt a 90 cent\u00edmetros; y que la presencialidad se dar\u00e1 siempre que la situaci\u00f3n epidemiol\u00f3gica del distrito as\u00ed lo permita.<\/p>\n\n\n\n<p>De hecho el gobierno indic\u00f3, con el plan, que la situaci\u00f3n de &#8220;todos los distritos bonaerenses lo permiten&#8221;.<\/p>\n\n\n\n<p>La vuelta a las clases con presencialidad plena conlleva igualmente continuar con los cuidados preventivos como el uso de tapabocas, ventilaci\u00f3n adecuada, higiene personas y de espacios f\u00edsicos de parte de trabajadores y de los propios alumnos.<\/p>\n\n\n\n<p>De hecho se remarca la necesidad de limpiar y desinfectar frecuentemente las dependencias, y que la distancia m\u00ednima entre docentes y alumnos sea de dos metros, entre otras exigencias que el plan establece para el regreso a las aulas con presencialidad plena.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes, a primera hora, la inspectora jefe distrital, Andrea Larrieu Lacoste inform\u00f3 a Cosas que pasan que transcurr\u00eda su \u00faltima jornada de trabajo, despu\u00e9s que se confirmara oficialmente su jubilaci\u00f3n. En este contexto se dio a conocer que el proceso del regreso a la presencialidad se dar\u00e1 de acuerdo a la situaci\u00f3n de cada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-28218","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paulatinamente comienza a aplicarse la presencialidad plena en Tres Arroyos - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paulatinamente comienza a aplicarse la presencialidad plena en Tres Arroyos - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"Este martes, a primera hora, la inspectora jefe distrital, Andrea Larrieu Lacoste inform\u00f3 a Cosas que pasan que transcurr\u00eda su \u00faltima jornada de trabajo, despu\u00e9s que se confirmara oficialmente su jubilaci\u00f3n. En este contexto se dio a conocer que el proceso del regreso a la presencialidad se dar\u00e1 de acuerdo a la situaci\u00f3n de cada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-01T01:45:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T01:45:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/02\/20200206135927_aulas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"887\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/\",\"name\":\"Paulatinamente comienza a aplicarse la presencialidad plena en Tres Arroyos - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"datePublished\":\"2021-09-01T01:45:25+00:00\",\"dateModified\":\"2021-09-01T01:45:26+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paulatinamente comienza a aplicarse la presencialidad plena en Tres Arroyos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paulatinamente comienza a aplicarse la presencialidad plena en Tres Arroyos - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/","og_locale":"es_ES","og_type":"article","og_title":"Paulatinamente comienza a aplicarse la presencialidad plena en Tres Arroyos - 103.9 fm","og_description":"Este martes, a primera hora, la inspectora jefe distrital, Andrea Larrieu Lacoste inform\u00f3 a Cosas que pasan que transcurr\u00eda su \u00faltima jornada de trabajo, despu\u00e9s que se confirmara oficialmente su jubilaci\u00f3n. En este contexto se dio a conocer que el proceso del regreso a la presencialidad se dar\u00e1 de acuerdo a la situaci\u00f3n de cada [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2021-09-01T01:45:25+00:00","article_modified_time":"2021-09-01T01:45:26+00:00","og_image":[{"width":887,"height":554,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/02\/20200206135927_aulas.jpg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/","url":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/","name":"Paulatinamente comienza a aplicarse la presencialidad plena en Tres Arroyos - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"datePublished":"2021-09-01T01:45:25+00:00","dateModified":"2021-09-01T01:45:26+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/31\/paulatinamente-comienza-a-aplicarse-la-presencialidad-plena-en-tres-arroyos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Paulatinamente comienza a aplicarse la presencialidad plena en Tres Arroyos"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/28218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=28218"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/28218\/revisions"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=28218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=28218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=28218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}