{"id":27813,"date":"2021-08-20T01:56:00","date_gmt":"2021-08-20T04:56:00","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=27813"},"modified":"2021-08-20T01:56:02","modified_gmt":"2021-08-20T04:56:02","slug":"reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/","title":{"rendered":"Reta: reuni\u00f3n de vecinos y autoridades por falta de seguridad"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-501811017\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>En el transcurso de este jueves, vecinos autoridades policiales y el delegado de la localidad balnearia, mantuvieron un encuentro motivados por la reiteraci\u00f3n de robos, y especialmente por las denuncias hechas en la sede policial de la localidad que no llegan a la fiscal\u00eda de Tres Arroyos.<\/p>\n\n\n\n<p>Recordamos que es a partir de las redes sociales, utilizadas por las mismas v\u00edctimas, c\u00f3mo toman estado p\u00fablico los hechos de inseguridad en la localidad tresarroyense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el transcurso de este jueves, vecinos autoridades policiales y el delegado de la localidad balnearia, mantuvieron un encuentro motivados por la reiteraci\u00f3n de robos, y especialmente por las denuncias hechas en la sede policial de la localidad que no llegan a la fiscal\u00eda de Tres Arroyos. Recordamos que es a partir de las redes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[29,35],"tags":[],"class_list":{"0":"post-27813","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales","8":"category-regionales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reta: reuni\u00f3n de vecinos y autoridades por falta de seguridad - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reta: reuni\u00f3n de vecinos y autoridades por falta de seguridad - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"En el transcurso de este jueves, vecinos autoridades policiales y el delegado de la localidad balnearia, mantuvieron un encuentro motivados por la reiteraci\u00f3n de robos, y especialmente por las denuncias hechas en la sede policial de la localidad que no llegan a la fiscal\u00eda de Tres Arroyos. Recordamos que es a partir de las redes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-20T04:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-20T04:56:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/01\/reta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/\",\"name\":\"Reta: reuni\u00f3n de vecinos y autoridades por falta de seguridad - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/01\/reta.jpg\",\"datePublished\":\"2021-08-20T04:56:00+00:00\",\"dateModified\":\"2021-08-20T04:56:02+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/01\/reta.jpg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/01\/reta.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reta: reuni\u00f3n de vecinos y autoridades por falta de seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reta: reuni\u00f3n de vecinos y autoridades por falta de seguridad - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/","og_locale":"es_ES","og_type":"article","og_title":"Reta: reuni\u00f3n de vecinos y autoridades por falta de seguridad - 103.9 fm","og_description":"En el transcurso de este jueves, vecinos autoridades policiales y el delegado de la localidad balnearia, mantuvieron un encuentro motivados por la reiteraci\u00f3n de robos, y especialmente por las denuncias hechas en la sede policial de la localidad que no llegan a la fiscal\u00eda de Tres Arroyos. Recordamos que es a partir de las redes [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2021-08-20T04:56:00+00:00","article_modified_time":"2021-08-20T04:56:02+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/01\/reta.jpg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/","url":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/","name":"Reta: reuni\u00f3n de vecinos y autoridades por falta de seguridad - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/01\/reta.jpg","datePublished":"2021-08-20T04:56:00+00:00","dateModified":"2021-08-20T04:56:02+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/01\/reta.jpg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/01\/reta.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/reta-reunion-de-vecinos-y-autoridades-por-falta-de-seguridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Reta: reuni\u00f3n de vecinos y autoridades por falta de seguridad"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/01\/reta.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=27813"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/4234"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=27813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=27813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=27813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}