{"id":27810,"date":"2021-08-20T01:43:22","date_gmt":"2021-08-20T04:43:22","guid":{"rendered":"https:\/\/ondauno.com.ar\/?p=27810"},"modified":"2021-08-20T01:51:50","modified_gmt":"2021-08-20T04:51:50","slug":"tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/","title":{"rendered":"Tres Arroyos sin seguridad: dispararon contra un joven y balearon dos viviendas"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-2220804245\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>En el transcurso de las dos \u00faltimas jornadas la Comisar\u00eda Primera recibi\u00f3 al menos tres denuncias con hechos violentos marcados por el uso de armas de fuego.<br>En uno de ellos se supo que este mi\u00e9rcoles a las once de la noche, un joven de 23 a\u00f1os de edad identificado como Kevin Bornaticci fue interceptado en la calle por un sujeto que le dispar\u00f3 con un arma de fuego recortada sin llegar a herirlo. El incidente ocurri\u00f3 en calle Cerrito 1600.<\/p>\n\n\n\n<p>Ese mismo d\u00eda y a la misma hora sucedi\u00f3 otro incidente con uso de arma de fuego<br>Una mujer identificada como Roxana Gijsberts de 34 a\u00f1os de edad, denunci\u00f3 que escucharon detonaciones en el patio trasero de su casa, que c\u00f3mo consecuencia le dejaron impactos contra una chapa que coloc\u00f3 para reforzar la ventana.<\/p>\n\n\n\n<p>Un hecho m\u00e1s fue denunciado y ocurri\u00f3 a las 0:30 de este jueves, cuando un hombre de 72 a\u00f1os a\u00f1os de edad identificado como Ra\u00fal Buono, advirti\u00f3 que su casa fue baleada desde el exterior, en calle Tierra 829.<br>En los tres casos investiga la fiscal\u00eda N13, que subroga el fiscal Gabriel Lopazzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el transcurso de las dos \u00faltimas jornadas la Comisar\u00eda Primera recibi\u00f3 al menos tres denuncias con hechos violentos marcados por el uso de armas de fuego.En uno de ellos se supo que este mi\u00e9rcoles a las once de la noche, un joven de 23 a\u00f1os de edad identificado como Kevin Bornaticci fue interceptado en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[29],"tags":[],"class_list":{"0":"post-27810","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tres Arroyos sin seguridad: dispararon contra un joven y balearon dos viviendas - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tres Arroyos sin seguridad: dispararon contra un joven y balearon dos viviendas - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"En el transcurso de las dos \u00faltimas jornadas la Comisar\u00eda Primera recibi\u00f3 al menos tres denuncias con hechos violentos marcados por el uso de armas de fuego.En uno de ellos se supo que este mi\u00e9rcoles a las once de la noche, un joven de 23 a\u00f1os de edad identificado como Kevin Bornaticci fue interceptado en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-20T04:43:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-20T04:51:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/07\/Poli-noche-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/\",\"name\":\"Tres Arroyos sin seguridad: dispararon contra un joven y balearon dos viviendas - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/07\/Poli-noche-2.jpg\",\"datePublished\":\"2021-08-20T04:43:22+00:00\",\"dateModified\":\"2021-08-20T04:51:50+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/07\/Poli-noche-2.jpg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/07\/Poli-noche-2.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tres Arroyos sin seguridad: dispararon contra un joven y balearon dos viviendas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tres Arroyos sin seguridad: dispararon contra un joven y balearon dos viviendas - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/","og_locale":"es_ES","og_type":"article","og_title":"Tres Arroyos sin seguridad: dispararon contra un joven y balearon dos viviendas - 103.9 fm","og_description":"En el transcurso de las dos \u00faltimas jornadas la Comisar\u00eda Primera recibi\u00f3 al menos tres denuncias con hechos violentos marcados por el uso de armas de fuego.En uno de ellos se supo que este mi\u00e9rcoles a las once de la noche, un joven de 23 a\u00f1os de edad identificado como Kevin Bornaticci fue interceptado en [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2021-08-20T04:43:22+00:00","article_modified_time":"2021-08-20T04:51:50+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/07\/Poli-noche-2.jpg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/","url":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/","name":"Tres Arroyos sin seguridad: dispararon contra un joven y balearon dos viviendas - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/07\/Poli-noche-2.jpg","datePublished":"2021-08-20T04:43:22+00:00","dateModified":"2021-08-20T04:51:50+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/07\/Poli-noche-2.jpg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/07\/Poli-noche-2.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/08\/20\/tres-arroyos-sin-seguridad-dispararon-contra-un-joven-y-balearon-dos-viviendas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Tres Arroyos sin seguridad: dispararon contra un joven y balearon dos viviendas"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/07\/Poli-noche-2.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=27810"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/27123"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=27810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=27810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=27810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}