{"id":25651,"date":"2021-06-02T14:37:02","date_gmt":"2021-06-02T17:37:02","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=25651"},"modified":"2021-06-02T14:39:34","modified_gmt":"2021-06-02T17:39:34","slug":"el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/","title":{"rendered":"El radicalismo contact\u00f3 a \u00c1vila, para sumarlo a Juntos por el Cambio"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-768432997\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>Un segmento de la Uni\u00f3n C\u00edvica Radical invit\u00f3 al ex director del Organismo Descentralizado Claromec\u00f3 Servicios Tur\u00edsticos, Carlos \u00c1vila, a incorporarse -como extra partidario- dentro de sus filas y en consecuencia pasar a formar parte de la coalici\u00f3n de Juntos por el Cambio en Tres Arroyos, pensando en las pr\u00f3ximas elecciones legislativas.<\/p>\n\n\n\n<p>Hasta el momento, el ex funcionario claromequense no hab\u00eda sido asociado a ning\u00fan otro partido que no fuera el oficialismo local; aunque siempre desde la oposici\u00f3n se reconoci\u00f3 el nivel de su gesti\u00f3n en la localidad balnearia.<\/p>\n\n\n\n<p>El encargado de hacerle llegar la propuesta fue el actual Presidente del Comit\u00e9 Enrique Betolaza, Gonzalo Cabrera, que espera poder contar con su presencia dentro del partido al cual pretende abrir, para lograr la participaci\u00f3n de personalidades tales como la de \u00c1vila, quien recibi\u00f3 de buena manera la propuesta pero que a\u00fan no dio una respuesta  al respecto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un segmento de la Uni\u00f3n C\u00edvica Radical invit\u00f3 al ex director del Organismo Descentralizado Claromec\u00f3 Servicios Tur\u00edsticos, Carlos \u00c1vila, a incorporarse -como extra partidario- dentro de sus filas y en consecuencia pasar a formar parte de la coalici\u00f3n de Juntos por el Cambio en Tres Arroyos, pensando en las pr\u00f3ximas elecciones legislativas. Hasta el momento, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-25651","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El radicalismo contact\u00f3 a \u00c1vila, para sumarlo a Juntos por el Cambio - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El radicalismo contact\u00f3 a \u00c1vila, para sumarlo a Juntos por el Cambio - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"Un segmento de la Uni\u00f3n C\u00edvica Radical invit\u00f3 al ex director del Organismo Descentralizado Claromec\u00f3 Servicios Tur\u00edsticos, Carlos \u00c1vila, a incorporarse -como extra partidario- dentro de sus filas y en consecuencia pasar a formar parte de la coalici\u00f3n de Juntos por el Cambio en Tres Arroyos, pensando en las pr\u00f3ximas elecciones legislativas. Hasta el momento, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-02T17:37:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-02T17:39:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/04\/lvp.avila2_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"859\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/\",\"name\":\"El radicalismo contact\u00f3 a \u00c1vila, para sumarlo a Juntos por el Cambio - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/04\/lvp.avila2_.jpg\",\"datePublished\":\"2021-06-02T17:37:02+00:00\",\"dateModified\":\"2021-06-02T17:39:34+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/04\/lvp.avila2_.jpg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/04\/lvp.avila2_.jpg\",\"width\":768,\"height\":859},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El radicalismo contact\u00f3 a \u00c1vila, para sumarlo a Juntos por el Cambio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El radicalismo contact\u00f3 a \u00c1vila, para sumarlo a Juntos por el Cambio - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/","og_locale":"es_ES","og_type":"article","og_title":"El radicalismo contact\u00f3 a \u00c1vila, para sumarlo a Juntos por el Cambio - 103.9 fm","og_description":"Un segmento de la Uni\u00f3n C\u00edvica Radical invit\u00f3 al ex director del Organismo Descentralizado Claromec\u00f3 Servicios Tur\u00edsticos, Carlos \u00c1vila, a incorporarse -como extra partidario- dentro de sus filas y en consecuencia pasar a formar parte de la coalici\u00f3n de Juntos por el Cambio en Tres Arroyos, pensando en las pr\u00f3ximas elecciones legislativas. Hasta el momento, [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2021-06-02T17:37:02+00:00","article_modified_time":"2021-06-02T17:39:34+00:00","og_image":[{"width":768,"height":859,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/04\/lvp.avila2_.jpg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/","url":"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/","name":"El radicalismo contact\u00f3 a \u00c1vila, para sumarlo a Juntos por el Cambio - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/04\/lvp.avila2_.jpg","datePublished":"2021-06-02T17:37:02+00:00","dateModified":"2021-06-02T17:39:34+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/04\/lvp.avila2_.jpg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/04\/lvp.avila2_.jpg","width":768,"height":859},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/06\/02\/el-radicalismo-contacto-a-avila-para-sumarlo-a-juntos-por-el-cambio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"El radicalismo contact\u00f3 a \u00c1vila, para sumarlo a Juntos por el Cambio"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/04\/lvp.avila2_.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/25651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=25651"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/25651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/8536"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=25651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=25651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=25651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}