{"id":23471,"date":"2021-03-16T11:57:46","date_gmt":"2021-03-16T14:57:46","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=23471"},"modified":"2021-03-16T13:54:34","modified_gmt":"2021-03-16T16:54:34","slug":"tres-arroyos-sigue-en-fase-4-2","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/","title":{"rendered":"Bianco y Gollan presentaron la situaci\u00f3n epidemiol\u00f3gica, podr\u00eda habilitarse el f\u00fatbol regional.   Tres Arroyos en fase 4"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-332272244\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El Jefe de Gabinete y el Ministro de Salud bonaerenses se\u00f1alaron que los casos siguen en aumento e instaron a reforzar los cuidados y las medidas de prevenci\u00f3n mientras avanza el plan Buenos Aires Vacunate, que ya super\u00f3 el mill\u00f3n de aplicaciones.<\/h2>\n\n\n\n<p>El jefe de Gabinete, Carlos Bianco, y el ministro de Salud, Daniel Gollan, brindaron detalles sobre la situaci\u00f3n epidemiol\u00f3gica y sanitaria en la provincia de Buenos Aires y el esquema de fases de aislamiento y distanciamiento social, preventivo y obligatorio en los 135 distritos bonaerenses. <\/p>\n\n\n\n<p>En la conferencia de prensa realizada en el Sal\u00f3n Dorado de la Gobernaci\u00f3n bonaerense, el ministro Gollan indic\u00f3 que en la \u00faltima semana se registr\u00f3 un nuevo aumento en la cantidad de casos, que se ubicaron en un promedio diario de 2.763 (frente a los 2.594 de la semana previa). Gollan explic\u00f3 que en las \u00faltimas dos semanas se produjo un incremento sostenido en el \u00c1rea Metropolitana de Buenos Aires (AMBA) y se\u00f1al\u00f3 la preocupaci\u00f3n por que el aumento se traslade en las pr\u00f3ximas semanas al interior de la provincia. Si bien por ahora el nivel de ocupaci\u00f3n de camas de cuidados intensivos se mantiene estable, \u201ces necesario recordar que el aumento de casos repercute hasta dos y tres semanas despu\u00e9s en el sistema sanitario\u201d, afirm\u00f3 el ministro.<\/p>\n\n\n\n<p>En referencia al avance del plan Buenos Aires Vacunate, Gollan destac\u00f3 que se ha superado el mill\u00f3n de dosis aplicadas, de las cuales 830.704 corresponden al componente uno y 188.862 al componente dos. \u201cEsta campa\u00f1a est\u00e1 siendo muy ordenada y ejecutada de una manera excelente, no solo en cuanto a calidad, sino en cuanto a calidez\u201d, afirm\u00f3 el ministro.<\/p>\n\n\n\n<p>Por otro lado, Gollan advirti\u00f3 sobre las nuevas cepas que aparecen en pa\u00edses de la regi\u00f3n, como el caso de la conocida como \u201cManaos\u201d. El ministro se\u00f1al\u00f3 que \u201ctrabajamos fuertemente para ver c\u00f3mo se restringe al m\u00e1ximo la posibilidad de que esa cepa ingrese al territorio bonaerense\u201d. \u201cSi no cuidamos mucho todo lo que logramos y aparece una variante mucho m\u00e1s contagiosa, lo podemos llegar a perder. Trabajemos para que eso no suceda, mantengamos los cuidados, no nos podemos relajar\u201d, concluy\u00f3 Gollan.<\/p>\n\n\n\n<p>Bianco, por su parte, present\u00f3 la situaci\u00f3n del esquema de fases en la provincia: 109 municipios se encuentran en fase 4 y 26 en fase 5. <strong>El Jefe de Gabinete se refiri\u00f3, asimismo, a la reuni\u00f3n que mantuvo ayer con el presidente de la Asociaci\u00f3n del F\u00fatbol Argentino, Claudio Tapia, en la que se trat\u00f3 la posibilidad de habilitar, a partir del 1\u00b0 de abril, el f\u00fatbol federado de las ligas regionales bonaerenses, siguiendo estrictos cuidados y sin p\u00fablico. <\/strong>Finalmente, Bianco se\u00f1al\u00f3 que se est\u00e1 trabajando en conjunto con la ministra de Gobierno, Teresa Garc\u00eda, para brindar colaboraci\u00f3n en la implementaci\u00f3n de protocolos para el desarrollo de las elecciones internas de la Uni\u00f3n C\u00edvica Radical que se celebrar\u00e1n el pr\u00f3ximo domingo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/bianco-informe-1024x681.jpg\" alt=\"\" class=\"wp-image-23487 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/681;\" \/><noscript><img decoding=\"async\" src=\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/bianco-informe-1024x681.jpg\" alt=\"\" class=\"wp-image-23487\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0007-1024x577.jpg\" alt=\"\" class=\"wp-image-23472 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/577;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0007-1024x577.jpg\" alt=\"\" class=\"wp-image-23472\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0008-1024x577.jpg\" alt=\"\" class=\"wp-image-23473 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/577;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0008-1024x577.jpg\" alt=\"\" class=\"wp-image-23473\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0003-1024x577.jpg\" alt=\"\" class=\"wp-image-23474 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/577;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0003-1024x577.jpg\" alt=\"\" class=\"wp-image-23474\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0004-1024x577.jpg\" alt=\"\" class=\"wp-image-23475 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/577;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0004-1024x577.jpg\" alt=\"\" class=\"wp-image-23475\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0005-1024x577.jpg\" alt=\"\" class=\"wp-image-23476 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/577;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0005-1024x577.jpg\" alt=\"\" class=\"wp-image-23476\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0006-1024x577.jpg\" alt=\"\" class=\"wp-image-23477 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/577;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Fases_aislamiento_16_03_21_page-0006-1024x577.jpg\" alt=\"\" class=\"wp-image-23477\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0008-1024x576.jpg\" alt=\"\" class=\"wp-image-23478 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0008-1024x576.jpg\" alt=\"\" class=\"wp-image-23478\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0009-1024x576.jpg\" alt=\"\" class=\"wp-image-23479 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0009-1024x576.jpg\" alt=\"\" class=\"wp-image-23479\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0010-1024x576.jpg\" alt=\"\" class=\"wp-image-23480 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0010-1024x576.jpg\" alt=\"\" class=\"wp-image-23480\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0011-1024x576.jpg\" alt=\"\" class=\"wp-image-23481 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0011-1024x576.jpg\" alt=\"\" class=\"wp-image-23481\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0012-1024x576.jpg\" alt=\"\" class=\"wp-image-23482 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0012-1024x576.jpg\" alt=\"\" class=\"wp-image-23482\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0002-1024x576.jpg\" alt=\"\" class=\"wp-image-23483 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0002-1024x576.jpg\" alt=\"\" class=\"wp-image-23483\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0004-1024x576.jpg\" alt=\"\" class=\"wp-image-23484 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0004-1024x576.jpg\" alt=\"\" class=\"wp-image-23484\"\/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0003-1024x576.jpg\" alt=\"\" class=\"wp-image-23485 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/Conferencia-16_03_page-0003-1024x576.jpg\" alt=\"\" class=\"wp-image-23485\"\/><\/noscript><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Jefe de Gabinete y el Ministro de Salud bonaerenses se\u00f1alaron que los casos siguen en aumento e instaron a reforzar los cuidados y las medidas de prevenci\u00f3n mientras avanza el plan Buenos Aires Vacunate, que ya super\u00f3 el mill\u00f3n de aplicaciones. El jefe de Gabinete, Carlos Bianco, y el ministro de Salud, Daniel Gollan, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[30],"tags":[],"class_list":{"0":"post-23471","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-provinciales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bianco y Gollan presentaron la situaci\u00f3n epidemiol\u00f3gica, podr\u00eda habilitarse el f\u00fatbol regional.  Tres Arroyos en fase 4 - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bianco y Gollan presentaron la situaci\u00f3n epidemiol\u00f3gica, podr\u00eda habilitarse el f\u00fatbol regional.  Tres Arroyos en fase 4 - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"El Jefe de Gabinete y el Ministro de Salud bonaerenses se\u00f1alaron que los casos siguen en aumento e instaron a reforzar los cuidados y las medidas de prevenci\u00f3n mientras avanza el plan Buenos Aires Vacunate, que ya super\u00f3 el mill\u00f3n de aplicaciones. El jefe de Gabinete, Carlos Bianco, y el ministro de Salud, Daniel Gollan, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-16T14:57:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-16T16:54:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/bianco-gollan-hoy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1733\" \/>\n\t<meta property=\"og:image:height\" content=\"1153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/\",\"name\":\"Bianco y Gollan presentaron la situaci\u00f3n epidemiol\u00f3gica, podr\u00eda habilitarse el f\u00fatbol regional. Tres Arroyos en fase 4 - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/bianco-informe-1024x681.jpg\",\"datePublished\":\"2021-03-16T14:57:46+00:00\",\"dateModified\":\"2021-03-16T16:54:34+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bianco y Gollan presentaron la situaci\u00f3n epidemiol\u00f3gica, podr\u00eda habilitarse el f\u00fatbol regional. Tres Arroyos en fase 4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bianco y Gollan presentaron la situaci\u00f3n epidemiol\u00f3gica, podr\u00eda habilitarse el f\u00fatbol regional.  Tres Arroyos en fase 4 - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/","og_locale":"es_ES","og_type":"article","og_title":"Bianco y Gollan presentaron la situaci\u00f3n epidemiol\u00f3gica, podr\u00eda habilitarse el f\u00fatbol regional.  Tres Arroyos en fase 4 - 103.9 fm","og_description":"El Jefe de Gabinete y el Ministro de Salud bonaerenses se\u00f1alaron que los casos siguen en aumento e instaron a reforzar los cuidados y las medidas de prevenci\u00f3n mientras avanza el plan Buenos Aires Vacunate, que ya super\u00f3 el mill\u00f3n de aplicaciones. El jefe de Gabinete, Carlos Bianco, y el ministro de Salud, Daniel Gollan, [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2021-03-16T14:57:46+00:00","article_modified_time":"2021-03-16T16:54:34+00:00","og_image":[{"width":1733,"height":1153,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/bianco-gollan-hoy.jpg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/","url":"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/","name":"Bianco y Gollan presentaron la situaci\u00f3n epidemiol\u00f3gica, podr\u00eda habilitarse el f\u00fatbol regional. Tres Arroyos en fase 4 - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/#primaryimage"},"thumbnailUrl":"http:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/03\/bianco-informe-1024x681.jpg","datePublished":"2021-03-16T14:57:46+00:00","dateModified":"2021-03-16T16:54:34+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/03\/16\/tres-arroyos-sigue-en-fase-4-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Bianco y Gollan presentaron la situaci\u00f3n epidemiol\u00f3gica, podr\u00eda habilitarse el f\u00fatbol regional. Tres Arroyos en fase 4"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/23471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=23471"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/23471\/revisions"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=23471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=23471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=23471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}