{"id":22651,"date":"2021-02-20T00:23:19","date_gmt":"2021-02-20T03:23:19","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=22651"},"modified":"2021-02-20T00:41:08","modified_gmt":"2021-02-20T03:41:08","slug":"denuncian-la-existencia-de-escuelas-sin-condiciones","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/","title":{"rendered":"Denuncian la existencia de \u201cescuelas sin condiciones\u201d"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-2535411092\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>\u201cEsta semana, docentes y auxiliares preocupados se comunicaron conmigo para exponer la situaci\u00f3n de sus escuelas: ba\u00f1os sin condiciones, ausencia o falla de insumos y, quiz\u00e1s lo m\u00e1s grave, falta de agua\u201d, comienza un escrito que comparti\u00f3 en sus redes sociales el concejal Mart\u00edn Garate.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/02\/73209067_10220328679957923_4795748392380661760_o-1.jpg\" alt=\"\" class=\"wp-image-22655 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/02\/73209067_10220328679957923_4795748392380661760_o-1.jpg\" alt=\"\" class=\"wp-image-22655\"\/><\/noscript><\/figure>\n\n\n\n<p>El titular de la bancada de Todos, explic\u00f3 que \u201cel viernes pasado solicitamos al Consejo Escolar un informe para que nos aseguren que todas las escuelas iban a tener las condiciones e insumos que necesitaban. A pesar de recibir respuesta, vemos que no se garantiz\u00f3 algo tan b\u00e1sico como el agua potable\u201d, sostuvo.<br>En consecuencia, Garate, se\u00f1al\u00f3 que el motivo de sus expresiones son \u201cun llamado a la reflexi\u00f3n\u201d. <\/p>\n\n\n\n<p>Entiende que \u201cno es reciente el estado de abandono que tienen los edificios escolares, pero este contexto que estamos viviendo lo hizo m\u00e1s evidente. Usemos este impulso para que esta situaci\u00f3n mejore. Los docentes, el personal no docente y los chicos deben tener asegurado un paso por las instituciones de formaci\u00f3n con condiciones humanas\u201d, reclam\u00f3.<br> Finalmente expres\u00f3 que desde su rol de concejal est\u00e1 \u201ccomprometido y trabajando para que se avance en este sentido y que el d\u00eda de ma\u00f1ana tengamos una Educaci\u00f3n digna para todos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEsta semana, docentes y auxiliares preocupados se comunicaron conmigo para exponer la situaci\u00f3n de sus escuelas: ba\u00f1os sin condiciones, ausencia o falla de insumos y, quiz\u00e1s lo m\u00e1s grave, falta de agua\u201d, comienza un escrito que comparti\u00f3 en sus redes sociales el concejal Mart\u00edn Garate. El titular de la bancada de Todos, explic\u00f3 que \u201cel [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-22651","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Denuncian la existencia de \u201cescuelas sin condiciones\u201d - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Denuncian la existencia de \u201cescuelas sin condiciones\u201d - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"\u201cEsta semana, docentes y auxiliares preocupados se comunicaron conmigo para exponer la situaci\u00f3n de sus escuelas: ba\u00f1os sin condiciones, ausencia o falla de insumos y, quiz\u00e1s lo m\u00e1s grave, falta de agua\u201d, comienza un escrito que comparti\u00f3 en sus redes sociales el concejal Mart\u00edn Garate. El titular de la bancada de Todos, explic\u00f3 que \u201cel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-20T03:23:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-20T03:41:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/02\/garate-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"409\" \/>\n\t<meta property=\"og:image:height\" content=\"296\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/\",\"name\":\"Denuncian la existencia de \u201cescuelas sin condiciones\u201d - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/02\/73209067_10220328679957923_4795748392380661760_o-1.jpg\",\"datePublished\":\"2021-02-20T03:23:19+00:00\",\"dateModified\":\"2021-02-20T03:41:08+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Denuncian la existencia de \u201cescuelas sin condiciones\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Denuncian la existencia de \u201cescuelas sin condiciones\u201d - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/","og_locale":"es_ES","og_type":"article","og_title":"Denuncian la existencia de \u201cescuelas sin condiciones\u201d - 103.9 fm","og_description":"\u201cEsta semana, docentes y auxiliares preocupados se comunicaron conmigo para exponer la situaci\u00f3n de sus escuelas: ba\u00f1os sin condiciones, ausencia o falla de insumos y, quiz\u00e1s lo m\u00e1s grave, falta de agua\u201d, comienza un escrito que comparti\u00f3 en sus redes sociales el concejal Mart\u00edn Garate. El titular de la bancada de Todos, explic\u00f3 que \u201cel [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2021-02-20T03:23:19+00:00","article_modified_time":"2021-02-20T03:41:08+00:00","og_image":[{"width":409,"height":296,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/02\/garate-1.jpg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/","url":"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/","name":"Denuncian la existencia de \u201cescuelas sin condiciones\u201d - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/02\/73209067_10220328679957923_4795748392380661760_o-1.jpg","datePublished":"2021-02-20T03:23:19+00:00","dateModified":"2021-02-20T03:41:08+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/02\/20\/denuncian-la-existencia-de-escuelas-sin-condiciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Denuncian la existencia de \u201cescuelas sin condiciones\u201d"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=22651"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22651\/revisions"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=22651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=22651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=22651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}