{"id":21754,"date":"2021-01-14T12:28:32","date_gmt":"2021-01-14T15:28:32","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=21754"},"modified":"2021-01-14T12:28:37","modified_gmt":"2021-01-14T15:28:37","slug":"recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/","title":{"rendered":"Recomiendan &#8220;fijar arena, pero lo menos posible&#8221; en las costas del distrito"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-118320616\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>El Dr. en Geolog\u00eda e investigador del CONICET, Federico Ignacio Isla, habl\u00f3 en Cosas que pasan sobre los resultados de un reciente informe publicado en donde se advierte como afecta la erosi\u00f3n costera en la provincia de Buenos Aires. <br><\/p>\n\n\n\n<p>Tambi\u00e9n habl\u00f3 espec\u00edficamente de la situaci\u00f3n de la costa tresarroyense.<\/p>\n\n\n\n<figure><iframe loading=\"lazy\" data-src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fwww.facebook.com%2Fondauno103.9%2Fvideos%2F400612331197865%2F&amp;show_text=false&amp;width=560\" width=\"560\" height=\"314\" allowfullscreen=\"true\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Dr. en Geolog\u00eda e investigador del CONICET, Federico Ignacio Isla, habl\u00f3 en Cosas que pasan sobre los resultados de un reciente informe publicado en donde se advierte como afecta la erosi\u00f3n costera en la provincia de Buenos Aires. Tambi\u00e9n habl\u00f3 espec\u00edficamente de la situaci\u00f3n de la costa tresarroyense.<\/p>\n","protected":false},"author":2,"featured_media":21755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26],"tags":[],"class_list":{"0":"post-21754","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacada"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Recomiendan &quot;fijar arena, pero lo menos posible&quot; en las costas del distrito - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recomiendan &quot;fijar arena, pero lo menos posible&quot; en las costas del distrito - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"El Dr. en Geolog\u00eda e investigador del CONICET, Federico Ignacio Isla, habl\u00f3 en Cosas que pasan sobre los resultados de un reciente informe publicado en donde se advierte como afecta la erosi\u00f3n costera en la provincia de Buenos Aires. Tambi\u00e9n habl\u00f3 espec\u00edficamente de la situaci\u00f3n de la costa tresarroyense.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-14T15:28:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-14T15:28:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-14-at-12.18.31.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1227\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/\",\"name\":\"Recomiendan \\\"fijar arena, pero lo menos posible\\\" en las costas del distrito - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-14-at-12.18.31.jpeg\",\"datePublished\":\"2021-01-14T15:28:32+00:00\",\"dateModified\":\"2021-01-14T15:28:37+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-14-at-12.18.31.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-14-at-12.18.31.jpeg\",\"width\":1280,\"height\":1227},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recomiendan &#8220;fijar arena, pero lo menos posible&#8221; en las costas del distrito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recomiendan \"fijar arena, pero lo menos posible\" en las costas del distrito - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/","og_locale":"es_ES","og_type":"article","og_title":"Recomiendan \"fijar arena, pero lo menos posible\" en las costas del distrito - 103.9 fm","og_description":"El Dr. en Geolog\u00eda e investigador del CONICET, Federico Ignacio Isla, habl\u00f3 en Cosas que pasan sobre los resultados de un reciente informe publicado en donde se advierte como afecta la erosi\u00f3n costera en la provincia de Buenos Aires. Tambi\u00e9n habl\u00f3 espec\u00edficamente de la situaci\u00f3n de la costa tresarroyense.","og_url":"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2021-01-14T15:28:32+00:00","article_modified_time":"2021-01-14T15:28:37+00:00","og_image":[{"width":1280,"height":1227,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-14-at-12.18.31.jpeg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/","url":"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/","name":"Recomiendan \"fijar arena, pero lo menos posible\" en las costas del distrito - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-14-at-12.18.31.jpeg","datePublished":"2021-01-14T15:28:32+00:00","dateModified":"2021-01-14T15:28:37+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-14-at-12.18.31.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-14-at-12.18.31.jpeg","width":1280,"height":1227},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2021\/01\/14\/recomiendan-fijar-arena-pero-lo-menos-posible-en-las-costas-del-distrito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Recomiendan &#8220;fijar arena, pero lo menos posible&#8221; en las costas del distrito"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-14-at-12.18.31.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/21754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=21754"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/21754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/21755"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=21754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=21754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=21754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}