{"id":21245,"date":"2020-12-29T10:07:35","date_gmt":"2020-12-29T13:07:35","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=21245"},"modified":"2020-12-29T10:07:41","modified_gmt":"2020-12-29T13:07:41","slug":"en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/","title":{"rendered":"En Claromec\u00f3, la polic\u00eda clausur\u00f3 otra fiesta clandestina en la playa"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-3731069838\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><br> Durante la madrugada de hoy -a las 04:45- personal policial de Claromec\u00f3 abocado a las recorridas en prevenci\u00f3n de delitos, localiz\u00f3 a unos 3 km en direcci\u00f3n a Orense -y en zona de m\u00e9danos- la realizaci\u00f3n de una nueva fiesta clandestina con la concurrencia de unas 150 personas y 30 veh\u00edculos. <br> Los efectivos realizaron un corte total de los accesos con el objetivo de evitar el paso de m\u00e1s concurrentes y se mantuvo distancia a los fines de no confrontar y proceder a la identificaci\u00f3n de los organizadores del evento que resultaron ser dos menores de 16 a\u00f1os de edad.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-21246 lazyload\" data-srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-1024x768.jpeg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-300x225.jpeg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-768x576.jpeg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-80x60.jpeg 80w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-265x198.jpeg 265w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-696x522.jpeg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-560x420.jpeg 560w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1.jpeg 1032w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-21246\" srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-1024x768.jpeg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-300x225.jpeg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-768x576.jpeg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-80x60.jpeg 80w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-265x198.jpeg 265w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-696x522.jpeg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1-560x420.jpeg 560w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04-1.jpeg 1032w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<p><br> Interviene el Juzgado Federal Necochea a cargo del Dr. P\u00e9rez quien no dispuso medida alguna para con los menores, pero se confeccion\u00f3 un acta de infracci\u00f3n y se secuestraron dos parlantes, un tripode, una consola, un ecualizador, ocho juegos de luces; cables de conexi\u00f3n y grupo electr\u00f3geno . Interviene tambi\u00e9n el Juzgado de Faltas de Tres Arroyos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la madrugada de hoy -a las 04:45- personal policial de Claromec\u00f3 abocado a las recorridas en prevenci\u00f3n de delitos, localiz\u00f3 a unos 3 km en direcci\u00f3n a Orense -y en zona de m\u00e9danos- la realizaci\u00f3n de una nueva fiesta clandestina con la concurrencia de unas 150 personas y 30 veh\u00edculos. Los efectivos realizaron un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2,29],"tags":[],"class_list":{"0":"post-21245","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales","8":"category-policiales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Claromec\u00f3, la polic\u00eda clausur\u00f3 otra fiesta clandestina en la playa - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Claromec\u00f3, la polic\u00eda clausur\u00f3 otra fiesta clandestina en la playa - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"Durante la madrugada de hoy -a las 04:45- personal policial de Claromec\u00f3 abocado a las recorridas en prevenci\u00f3n de delitos, localiz\u00f3 a unos 3 km en direcci\u00f3n a Orense -y en zona de m\u00e9danos- la realizaci\u00f3n de una nueva fiesta clandestina con la concurrencia de unas 150 personas y 30 veh\u00edculos. Los efectivos realizaron un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-29T13:07:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-29T13:07:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/\",\"name\":\"En Claromec\u00f3, la polic\u00eda clausur\u00f3 otra fiesta clandestina en la playa - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04.jpeg\",\"datePublished\":\"2020-12-29T13:07:35+00:00\",\"dateModified\":\"2020-12-29T13:07:41+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04.jpeg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Claromec\u00f3, la polic\u00eda clausur\u00f3 otra fiesta clandestina en la playa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Claromec\u00f3, la polic\u00eda clausur\u00f3 otra fiesta clandestina en la playa - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/","og_locale":"es_ES","og_type":"article","og_title":"En Claromec\u00f3, la polic\u00eda clausur\u00f3 otra fiesta clandestina en la playa - 103.9 fm","og_description":"Durante la madrugada de hoy -a las 04:45- personal policial de Claromec\u00f3 abocado a las recorridas en prevenci\u00f3n de delitos, localiz\u00f3 a unos 3 km en direcci\u00f3n a Orense -y en zona de m\u00e9danos- la realizaci\u00f3n de una nueva fiesta clandestina con la concurrencia de unas 150 personas y 30 veh\u00edculos. Los efectivos realizaron un [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2020-12-29T13:07:35+00:00","article_modified_time":"2020-12-29T13:07:41+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04.jpeg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/","url":"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/","name":"En Claromec\u00f3, la polic\u00eda clausur\u00f3 otra fiesta clandestina en la playa - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04.jpeg","datePublished":"2020-12-29T13:07:35+00:00","dateModified":"2020-12-29T13:07:41+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04.jpeg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/12\/29\/en-claromeco-la-policia-clausuro-otra-fiesta-clandestina-en-la-playa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"En Claromec\u00f3, la polic\u00eda clausur\u00f3 otra fiesta clandestina en la playa"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-29-at-10.05.04.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/21245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=21245"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/21245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/21247"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=21245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=21245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=21245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}