{"id":17539,"date":"2020-10-12T18:23:37","date_gmt":"2020-10-12T21:23:37","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=17539"},"modified":"2020-10-12T18:23:41","modified_gmt":"2020-10-12T21:23:41","slug":"rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/","title":{"rendered":"Rompen una ventana lateral e ingresan a una Agencia de Loter\u00eda y Quiniela, se llevan 4000 pesos"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-2606253899\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>Una empleada de la Agencia de Loter\u00eda y Quiniela de la calle Hip\u00f3lito Irigoyen 136<br>denunci\u00f3 que entraron a robar en horas de la madrugada.<\/p>\n\n\n\n<p>Seg\u00fan la denunciante los malvivientes ingresaron a la Agencia de juego  por una ventana que se halla a un lado del comercio.<\/p>\n\n\n\n<p>La empleada identific\u00f3 el faltante de 4000 pesos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una empleada de la Agencia de Loter\u00eda y Quiniela de la calle Hip\u00f3lito Irigoyen 136denunci\u00f3 que entraron a robar en horas de la madrugada. Seg\u00fan la denunciante los malvivientes ingresaron a la Agencia de juego por una ventana que se halla a un lado del comercio. La empleada identific\u00f3 el faltante de 4000 pesos.<\/p>\n","protected":false},"author":2,"featured_media":17540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[29],"tags":[],"class_list":{"0":"post-17539","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rompen una ventana lateral e ingresan a una Agencia de Loter\u00eda y Quiniela, se llevan 4000 pesos - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rompen una ventana lateral e ingresan a una Agencia de Loter\u00eda y Quiniela, se llevan 4000 pesos - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"Una empleada de la Agencia de Loter\u00eda y Quiniela de la calle Hip\u00f3lito Irigoyen 136denunci\u00f3 que entraron a robar en horas de la madrugada. Seg\u00fan la denunciante los malvivientes ingresaron a la Agencia de juego por una ventana que se halla a un lado del comercio. La empleada identific\u00f3 el faltante de 4000 pesos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-12T21:23:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-12T21:23:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/10\/loterias.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/\",\"name\":\"Rompen una ventana lateral e ingresan a una Agencia de Loter\u00eda y Quiniela, se llevan 4000 pesos - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/10\/loterias.jpg\",\"datePublished\":\"2020-10-12T21:23:37+00:00\",\"dateModified\":\"2020-10-12T21:23:41+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/#primaryimage\",\"url\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/10\/loterias.jpg\",\"contentUrl\":\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/10\/loterias.jpg\",\"width\":540,\"height\":405},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rompen una ventana lateral e ingresan a una Agencia de Loter\u00eda y Quiniela, se llevan 4000 pesos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rompen una ventana lateral e ingresan a una Agencia de Loter\u00eda y Quiniela, se llevan 4000 pesos - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/","og_locale":"es_ES","og_type":"article","og_title":"Rompen una ventana lateral e ingresan a una Agencia de Loter\u00eda y Quiniela, se llevan 4000 pesos - 103.9 fm","og_description":"Una empleada de la Agencia de Loter\u00eda y Quiniela de la calle Hip\u00f3lito Irigoyen 136denunci\u00f3 que entraron a robar en horas de la madrugada. Seg\u00fan la denunciante los malvivientes ingresaron a la Agencia de juego por una ventana que se halla a un lado del comercio. La empleada identific\u00f3 el faltante de 4000 pesos.","og_url":"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2020-10-12T21:23:37+00:00","article_modified_time":"2020-10-12T21:23:41+00:00","og_image":[{"width":540,"height":405,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/10\/loterias.jpg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/","url":"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/","name":"Rompen una ventana lateral e ingresan a una Agencia de Loter\u00eda y Quiniela, se llevan 4000 pesos - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/#primaryimage"},"thumbnailUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/10\/loterias.jpg","datePublished":"2020-10-12T21:23:37+00:00","dateModified":"2020-10-12T21:23:41+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/#primaryimage","url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/10\/loterias.jpg","contentUrl":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/10\/loterias.jpg","width":540,"height":405},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/10\/12\/rompen-una-ventana-lateral-e-ingresan-a-una-agencia-de-loteria-y-quiniela-se-llevan-4000-pesos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Rompen una ventana lateral e ingresan a una Agencia de Loter\u00eda y Quiniela, se llevan 4000 pesos"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/10\/loterias.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/17539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=17539"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/17539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media\/17540"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=17539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=17539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=17539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}