{"id":11680,"date":"2020-06-28T15:28:08","date_gmt":"2020-06-28T18:28:08","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=11680"},"modified":"2020-06-28T15:28:09","modified_gmt":"2020-06-28T18:28:09","slug":"imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/","title":{"rendered":"Imputan a Telef\u00f3nica, Telecom y Telecentro por incumplimientos en el servicio"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-3182035192\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<table class=\"wp-block-table\"><tbody><tr><td><strong> <\/strong>Fueron las empresas con m\u00e1s reclamos de los consumidores durante mayo<br><br>Se las imputa por presunto incumplimiento en el servicio t\u00e9cnico, faltas administrativas y demoras\u00a0La Subsecretar\u00eda de Acciones para la Defensa de las y los Consumidores (SSADC), que depende de la Secretar\u00eda de Comercio Interior, imput\u00f3 a las empresas Telef\u00f3nica, Telecom y Telecentro por presunto incumplimientos en el\u00a0 servicio t\u00e9cnico, faltas administrativas y demoras en la entrega de productos.<br>\u00a0 \u00a0<br>A trav\u00e9s de los reclamos de las y los consumidores, la SSADC detect\u00f3 que el 22% de las denuncias ingresadas durante mayo en la Ventanilla \u00danica de Reclamos de Defensa del Consumidor y del Servicio de Conciliaci\u00f3n Previa en las Relaciones de Consumo fueron relativas a problemas con servicios de comunicaciones, convirti\u00e9ndose en el rubro que m\u00e1s quejas recibi\u00f3.\u00a0\u00a0<br><br>Seg\u00fan los reclamos, tanto Telef\u00f3nica de Argentina S.A. (Telef\u00f3nica y Movistar) como Telecom Argentina S.A. (Telecom, Personal, Fibertel y Cablevisi\u00f3n) y Telecentro S.A. brindar\u00edan un servicio t\u00e9cnico ineficiente debido a que no solucionan los desperfectos en las comunicaciones de telefon\u00eda, ni los inconvenientes en las conexiones de TV e internet. Adem\u00e1s, se excusaron en las restricciones que impone la emergencia sanitaria para no realizar reparaciones, a pesar de que las compa\u00f1\u00edas cuentan con protocolos espec\u00edficos que establecen pautas para el ingreso a los hogares, cuando es absolutamente indispensable.\u00a0<br><br>Las quejas a las tres empresas apuntaron tambi\u00e9n a incumplimientos administrativos ya que no realizar\u00edan el procesamiento de la baja del servicio o el cambio de plan en tiempo y forma y le generan al usuario deudas impropias.\u00a0<br><br>En el caso de Telef\u00f3nica, se sum\u00f3 la demora en los plazos de entrega de productos adquiridos y problemas con los tr\u00e1mites de portabilidad, ya que se indic\u00f3 que la compa\u00f1\u00eda no env\u00eda el chip, o lo hace con retrasos. Sin embargo, la facturaci\u00f3n del servicio se ejecuta como si el usuario estuviera disponiendo del producto con normalidad. Asimismo, se registraron inconvenientes con la ejecuci\u00f3n de la garant\u00eda de los productos adquiridos, ya que la empresa no informa y no arbitra los medios para soluciones excepcionales en el marco de la pandemia.\u00a0<br><br>En Telecentro, adem\u00e1s, los usuarios indicaron que los canales de atenci\u00f3n al p\u00fablico son deficientes, tanto telef\u00f3nicamente como a trav\u00e9s de la web. Una vez lograda la comunicaci\u00f3n pautan una cita al domicilio del consumidor, la cual incumplen en sucesivas oportunidades. Incluso se\u00f1alaron que no se le realizan los descuentos de los per\u00edodos en los cuales la empresa no les brind\u00f3 el servicio.\u00a0<br><br>Por su parte, la Secretaria de Comercio Interior Paula Espa\u00f1ol indic\u00f3: \u201cSon necesarios los reclamos formales de las y los consumidores para hacer efectivos sus derechos\u201d. Asimismo, se\u00f1al\u00f3: \u201cTras el an\u00e1lisis de las denuncias y al identificar la operatoria sistem\u00e1tica de las empresas, estamos actuando de oficio en representaci\u00f3n de todos los damnificados y encarando acciones administrativas o judiciales para que no se vulneren los derechos de las y los consumidores\u201d.<br><br>En este sentido, en los expedientes se agregaron las denuncias que permiten graficar que no se trata de problemas individuales, sino que son pr\u00e1cticas sistem\u00e1ticas que lesionan los derechos de un conjunto de consumidores, y los coloca en una situaci\u00f3n de mayor vulnerabilidad debido a que estos servicios se convirtieron en esenciales para la cotidianidad en el marco de la emergencia por la Pandemia.\u00a0<br><br>Todas las imputaciones por presuntas infracciones a la Ley de Defensa del Consumidor (Ley 24.240) fueron notificadas el 25 de junio y las empresas poseen 5 d\u00edas para ejercer su derecho a defensa.\u00a0<br><br>Las y los consumidores pueden escribir a\u00a0<a rel=\"noreferrer noopener\" href=\"mailto:co*******@co********.ar\" data-original-string=\"upMx\/WIID70VEmPoxRIj0BImLZ040S+KutaJhsdtEOk=\" title=\"This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.\" target=\"_blank\"><span \n                data-original-string=\"upMx\/WIID70VEmPoxRIj0BImLZ040S+KutaJhsdtEOk=\"\n                class=\"apbct-email-encoder\"\n                title=\"This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.\">co*******@co********.ar<\/span><\/a>\u00a0o en Twitter @DNDConsumidor. Tambi\u00e9n ingresar sus reclamos por incumplimientos en\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/nt.embluemail.com\/p\/cl?data=NEkPeLDJfupyk5aetE%2B5Ixej%2BUwCb%2Fbx%2BHpikUGH6koXE23Rii513xQol2ikcOgH8QMMEd1Nu%2Bi9j%2Fbfa4L6fIJXfNcAbcgeZtwE%2F1Zrmlc%3D!-!5j6!-!https%3A%2F%2Fwww.argentina.gob.ar%2Finiciar-un-reclamo-ante-defensa-de-las-y-los-consumidores%3Futm_source=emBlue%26utm_medium=email%26utm_campaign=Prensa%26utm_content=Imputacion+Telcos--Imputan+a+Telef%C3%B3nica%2C+Telecom+y+Telecentro+por+incumplimientos+en+el+servicio%26utm_term=multiple--7--none--40-50--ENVIO+SIMPLE\" target=\"_blank\">https:\/\/www.argentina.gob.ar\/iniciar-un-reclamo-ante-defensa-de-las-y-los-consumidores<\/a><br><\/td><\/tr><\/tbody><\/table>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/ci5.googleusercontent.com\/proxy\/5ksSiZHqtexyA5rPqDQnRUkLGfA5_hFFKyAmCKiMjCJ9E8RbiYXZW_ncBZnAbxcmp1btgLX1gpGlcDogO5zZ74bhfmdwSlULvtjJIDZlOKr5ZUJufdvfObgJmcV2Qbcff1_--alVVucM5Axo6uJQXYuDEulp6XGNALI6qKougIVV_GQ5KYMUwS39BES43LyleRu7HnVIeGR_jbK1QSWosQAGWd4=s0-d-e1-ft#https:\/\/nt.embluemail.com\/p\/op?data=WZ6%2BasSSpg8UJM7sXiwkhsuI9ESa7YRFM70MQOICJlCu5SDP%2B6Xy%2BeEjmfD6%2Fx4dnzbhB9cc8UWtO8SRbIh%2B9w%3D%3D!-!5j6\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" \/><noscript><img decoding=\"async\" src=\"https:\/\/ci5.googleusercontent.com\/proxy\/5ksSiZHqtexyA5rPqDQnRUkLGfA5_hFFKyAmCKiMjCJ9E8RbiYXZW_ncBZnAbxcmp1btgLX1gpGlcDogO5zZ74bhfmdwSlULvtjJIDZlOKr5ZUJufdvfObgJmcV2Qbcff1_--alVVucM5Axo6uJQXYuDEulp6XGNALI6qKougIVV_GQ5KYMUwS39BES43LyleRu7HnVIeGR_jbK1QSWosQAGWd4=s0-d-e1-ft#https:\/\/nt.embluemail.com\/p\/op?data=WZ6%2BasSSpg8UJM7sXiwkhsuI9ESa7YRFM70MQOICJlCu5SDP%2B6Xy%2BeEjmfD6%2Fx4dnzbhB9cc8UWtO8SRbIh%2B9w%3D%3D!-!5j6\" alt=\"\"\/><\/noscript><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Fueron las empresas con m\u00e1s reclamos de los consumidores durante mayo Se las imputa por presunto incumplimiento en el servicio t\u00e9cnico, faltas administrativas y demoras\u00a0La Subsecretar\u00eda de Acciones para la Defensa de las y los Consumidores (SSADC), que depende de la Secretar\u00eda de Comercio Interior, imput\u00f3 a las empresas Telef\u00f3nica, Telecom y Telecentro por presunto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":{"0":"post-11680","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-nacionales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Imputan a Telef\u00f3nica, Telecom y Telecentro por incumplimientos en el servicio - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imputan a Telef\u00f3nica, Telecom y Telecentro por incumplimientos en el servicio - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"Fueron las empresas con m\u00e1s reclamos de los consumidores durante mayo Se las imputa por presunto incumplimiento en el servicio t\u00e9cnico, faltas administrativas y demoras\u00a0La Subsecretar\u00eda de Acciones para la Defensa de las y los Consumidores (SSADC), que depende de la Secretar\u00eda de Comercio Interior, imput\u00f3 a las empresas Telef\u00f3nica, Telecom y Telecentro por presunto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-28T18:28:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-28T18:28:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/06\/telefonia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"289\" \/>\n\t<meta property=\"og:image:height\" content=\"174\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/\",\"name\":\"Imputan a Telef\u00f3nica, Telecom y Telecentro por incumplimientos en el servicio - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ci5.googleusercontent.com\/proxy\/5ksSiZHqtexyA5rPqDQnRUkLGfA5_hFFKyAmCKiMjCJ9E8RbiYXZW_ncBZnAbxcmp1btgLX1gpGlcDogO5zZ74bhfmdwSlULvtjJIDZlOKr5ZUJufdvfObgJmcV2Qbcff1_--alVVucM5Axo6uJQXYuDEulp6XGNALI6qKougIVV_GQ5KYMUwS39BES43LyleRu7HnVIeGR_jbK1QSWosQAGWd4=s0-d-e1-ft#https:\/\/nt.embluemail.com\/p\/op?data=WZ6%2BasSSpg8UJM7sXiwkhsuI9ESa7YRFM70MQOICJlCu5SDP%2B6Xy%2BeEjmfD6%2Fx4dnzbhB9cc8UWtO8SRbIh%2B9w%3D%3D!-!5j6\",\"datePublished\":\"2020-06-28T18:28:08+00:00\",\"dateModified\":\"2020-06-28T18:28:09+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/#primaryimage\",\"url\":\"https:\/\/ci5.googleusercontent.com\/proxy\/5ksSiZHqtexyA5rPqDQnRUkLGfA5_hFFKyAmCKiMjCJ9E8RbiYXZW_ncBZnAbxcmp1btgLX1gpGlcDogO5zZ74bhfmdwSlULvtjJIDZlOKr5ZUJufdvfObgJmcV2Qbcff1_--alVVucM5Axo6uJQXYuDEulp6XGNALI6qKougIVV_GQ5KYMUwS39BES43LyleRu7HnVIeGR_jbK1QSWosQAGWd4=s0-d-e1-ft#https:\/\/nt.embluemail.com\/p\/op?data=WZ6%2BasSSpg8UJM7sXiwkhsuI9ESa7YRFM70MQOICJlCu5SDP%2B6Xy%2BeEjmfD6%2Fx4dnzbhB9cc8UWtO8SRbIh%2B9w%3D%3D!-!5j6\",\"contentUrl\":\"https:\/\/ci5.googleusercontent.com\/proxy\/5ksSiZHqtexyA5rPqDQnRUkLGfA5_hFFKyAmCKiMjCJ9E8RbiYXZW_ncBZnAbxcmp1btgLX1gpGlcDogO5zZ74bhfmdwSlULvtjJIDZlOKr5ZUJufdvfObgJmcV2Qbcff1_--alVVucM5Axo6uJQXYuDEulp6XGNALI6qKougIVV_GQ5KYMUwS39BES43LyleRu7HnVIeGR_jbK1QSWosQAGWd4=s0-d-e1-ft#https:\/\/nt.embluemail.com\/p\/op?data=WZ6%2BasSSpg8UJM7sXiwkhsuI9ESa7YRFM70MQOICJlCu5SDP%2B6Xy%2BeEjmfD6%2Fx4dnzbhB9cc8UWtO8SRbIh%2B9w%3D%3D!-!5j6\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imputan a Telef\u00f3nica, Telecom y Telecentro por incumplimientos en el servicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imputan a Telef\u00f3nica, Telecom y Telecentro por incumplimientos en el servicio - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/","og_locale":"es_ES","og_type":"article","og_title":"Imputan a Telef\u00f3nica, Telecom y Telecentro por incumplimientos en el servicio - 103.9 fm","og_description":"Fueron las empresas con m\u00e1s reclamos de los consumidores durante mayo Se las imputa por presunto incumplimiento en el servicio t\u00e9cnico, faltas administrativas y demoras\u00a0La Subsecretar\u00eda de Acciones para la Defensa de las y los Consumidores (SSADC), que depende de la Secretar\u00eda de Comercio Interior, imput\u00f3 a las empresas Telef\u00f3nica, Telecom y Telecentro por presunto [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2020-06-28T18:28:08+00:00","article_modified_time":"2020-06-28T18:28:09+00:00","og_image":[{"width":289,"height":174,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/06\/telefonia.jpg","type":"image\/jpeg"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/","url":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/","name":"Imputan a Telef\u00f3nica, Telecom y Telecentro por incumplimientos en el servicio - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/#primaryimage"},"image":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/#primaryimage"},"thumbnailUrl":"https:\/\/ci5.googleusercontent.com\/proxy\/5ksSiZHqtexyA5rPqDQnRUkLGfA5_hFFKyAmCKiMjCJ9E8RbiYXZW_ncBZnAbxcmp1btgLX1gpGlcDogO5zZ74bhfmdwSlULvtjJIDZlOKr5ZUJufdvfObgJmcV2Qbcff1_--alVVucM5Axo6uJQXYuDEulp6XGNALI6qKougIVV_GQ5KYMUwS39BES43LyleRu7HnVIeGR_jbK1QSWosQAGWd4=s0-d-e1-ft#https:\/\/nt.embluemail.com\/p\/op?data=WZ6%2BasSSpg8UJM7sXiwkhsuI9ESa7YRFM70MQOICJlCu5SDP%2B6Xy%2BeEjmfD6%2Fx4dnzbhB9cc8UWtO8SRbIh%2B9w%3D%3D!-!5j6","datePublished":"2020-06-28T18:28:08+00:00","dateModified":"2020-06-28T18:28:09+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/#primaryimage","url":"https:\/\/ci5.googleusercontent.com\/proxy\/5ksSiZHqtexyA5rPqDQnRUkLGfA5_hFFKyAmCKiMjCJ9E8RbiYXZW_ncBZnAbxcmp1btgLX1gpGlcDogO5zZ74bhfmdwSlULvtjJIDZlOKr5ZUJufdvfObgJmcV2Qbcff1_--alVVucM5Axo6uJQXYuDEulp6XGNALI6qKougIVV_GQ5KYMUwS39BES43LyleRu7HnVIeGR_jbK1QSWosQAGWd4=s0-d-e1-ft#https:\/\/nt.embluemail.com\/p\/op?data=WZ6%2BasSSpg8UJM7sXiwkhsuI9ESa7YRFM70MQOICJlCu5SDP%2B6Xy%2BeEjmfD6%2Fx4dnzbhB9cc8UWtO8SRbIh%2B9w%3D%3D!-!5j6","contentUrl":"https:\/\/ci5.googleusercontent.com\/proxy\/5ksSiZHqtexyA5rPqDQnRUkLGfA5_hFFKyAmCKiMjCJ9E8RbiYXZW_ncBZnAbxcmp1btgLX1gpGlcDogO5zZ74bhfmdwSlULvtjJIDZlOKr5ZUJufdvfObgJmcV2Qbcff1_--alVVucM5Axo6uJQXYuDEulp6XGNALI6qKougIVV_GQ5KYMUwS39BES43LyleRu7HnVIeGR_jbK1QSWosQAGWd4=s0-d-e1-ft#https:\/\/nt.embluemail.com\/p\/op?data=WZ6%2BasSSpg8UJM7sXiwkhsuI9ESa7YRFM70MQOICJlCu5SDP%2B6Xy%2BeEjmfD6%2Fx4dnzbhB9cc8UWtO8SRbIh%2B9w%3D%3D!-!5j6"},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/28\/imputan-a-telefonica-telecom-y-telecentro-por-incumplimientos-en-el-servicio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"Imputan a Telef\u00f3nica, Telecom y Telecentro por incumplimientos en el servicio"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11680"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11680\/revisions"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}