{"id":11536,"date":"2020-06-23T20:16:01","date_gmt":"2020-06-23T23:16:01","guid":{"rendered":"http:\/\/ondauno.com.ar\/?p=11536"},"modified":"2020-06-23T20:16:04","modified_gmt":"2020-06-23T23:16:04","slug":"esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta","status":"publish","type":"post","link":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/","title":{"rendered":"\u00bfEST\u00c1 LISTO EL PA\u00cdS PARA LEVANTAR LA CUARENTENA Y APELAR A LA RESPONSABILIDAD SOCIAL, SEG\u00daN ESTA ENCUESTA?"},"content":{"rendered":"<div class=\"ondau-before-content_3\" style=\"margin-top: -30px;\" id=\"ondau-4126262383\"><a href=\"https:\/\/www.lps.com.ar\/\" aria-label=\"la-perse2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg\" alt=\"\"  srcset=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2.jpg 1353w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-300x43.jpg 300w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1024x148.jpg 1024w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-768x111.jpg 768w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-696x100.jpg 696w, https:\/\/ondauno.com.ar\/wp-content\/uploads\/2021\/10\/la-perse2-1068x154.jpg 1068w\" sizes=\"(max-width: 1353px) 100vw, 1353px\" class=\"no-lazyload\" width=\"1353\" height=\"195\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>El estudio se desarroll\u00f3 entre el 12 y el 16 de junio, a m\u00e1s de 1200 personas, residentes en el \u00c1rea Metropolitana de Buenos Aires, todos mayores de 16 a\u00f1os y al respecto, se obtuvieron los siguientes resultados:<\/p>\n\n\n\n<p>Fuente: Consultora Clivajes<\/p>\n\n\n\n<p><br>Cabe destacar que este 28 se vence la \u00faltima pr\u00f3rroga de la cuarentena decretada por el Gobierno nacional, y en ese marco, seg\u00fan lo sondeado, el &#8220;47% de los encuestados nos dice que debe flexibilizarse un poco para ir a trabajar, pero con controles estrictos, mientras que el 40% nos informa que no es momento de flexibilizar la cuarentena&#8221;.<\/p>\n\n\n\n<p>En Argentina, el confinamiento es muy dispar: en algunas de las grandes ciudades, crecen los n\u00fameros de contagios, y hasta preocupa la posibilidad de que el sistema sanitario no d\u00e9 a basto para brindar la atenci\u00f3n necesaria. En otros puntos del pa\u00eds, como las provincias de  Catamarca o Formosa, donde los casos son pocos o nulos, pueden reactivar algunas de las actividades y hasta juntarse en peque\u00f1os grupos de personas.<\/p>\n\n\n\n<p>Ello hace que a la hora de pensar en una posible extensi\u00f3n de la cuarentena, haya que pensar en la multiplicidad de realidades y factores que componen al pa\u00eds, para lograr responder a todos ellos de la mejor manera posible. Desde el Gobierno nacional han dado pocos indicios de c\u00f3mo podr\u00eda ser esa &#8220;salida&#8221; de la cuarentena, por lo que habr\u00e1 que esperar cu\u00e1l ser\u00e1 la definici\u00f3n el pr\u00f3ximo 28 cuando anuncien c\u00f3mo continuar\u00e1 la lucha contra la pandemia del coronavirus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El estudio se desarroll\u00f3 entre el 12 y el 16 de junio, a m\u00e1s de 1200 personas, residentes en el \u00c1rea Metropolitana de Buenos Aires, todos mayores de 16 a\u00f1os y al respecto, se obtuvieron los siguientes resultados: Fuente: Consultora Clivajes Cabe destacar que este 28 se vence la \u00faltima pr\u00f3rroga de la cuarentena decretada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":{"0":"post-11536","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-nacionales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfEST\u00c1 LISTO EL PA\u00cdS PARA LEVANTAR LA CUARENTENA Y APELAR A LA RESPONSABILIDAD SOCIAL, SEG\u00daN ESTA ENCUESTA? - 103.9 fm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEST\u00c1 LISTO EL PA\u00cdS PARA LEVANTAR LA CUARENTENA Y APELAR A LA RESPONSABILIDAD SOCIAL, SEG\u00daN ESTA ENCUESTA? - 103.9 fm\" \/>\n<meta property=\"og:description\" content=\"El estudio se desarroll\u00f3 entre el 12 y el 16 de junio, a m\u00e1s de 1200 personas, residentes en el \u00c1rea Metropolitana de Buenos Aires, todos mayores de 16 a\u00f1os y al respecto, se obtuvieron los siguientes resultados: Fuente: Consultora Clivajes Cabe destacar que este 28 se vence la \u00faltima pr\u00f3rroga de la cuarentena decretada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/\" \/>\n<meta property=\"og:site_name\" content=\"103.9 fm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ondauno103.9\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-23T23:16:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-23T23:16:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/06\/Sin-t\u00edtulo1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"973\" \/>\n\t<meta property=\"og:image:height\" content=\"543\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"fernando garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernando garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/\",\"url\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/\",\"name\":\"\u00bfEST\u00c1 LISTO EL PA\u00cdS PARA LEVANTAR LA CUARENTENA Y APELAR A LA RESPONSABILIDAD SOCIAL, SEG\u00daN ESTA ENCUESTA? - 103.9 fm\",\"isPartOf\":{\"@id\":\"https:\/\/ondauno.com.ar\/#website\"},\"datePublished\":\"2020-06-23T23:16:01+00:00\",\"dateModified\":\"2020-06-23T23:16:04+00:00\",\"author\":{\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\"},\"breadcrumb\":{\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ondauno.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEST\u00c1 LISTO EL PA\u00cdS PARA LEVANTAR LA CUARENTENA Y APELAR A LA RESPONSABILIDAD SOCIAL, SEG\u00daN ESTA ENCUESTA?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ondauno.com.ar\/#website\",\"url\":\"https:\/\/ondauno.com.ar\/\",\"name\":\"103.9 fm\",\"description\":\"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ondauno.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139\",\"name\":\"fernando garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g\",\"caption\":\"fernando garcia\"},\"url\":\"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEST\u00c1 LISTO EL PA\u00cdS PARA LEVANTAR LA CUARENTENA Y APELAR A LA RESPONSABILIDAD SOCIAL, SEG\u00daN ESTA ENCUESTA? - 103.9 fm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfEST\u00c1 LISTO EL PA\u00cdS PARA LEVANTAR LA CUARENTENA Y APELAR A LA RESPONSABILIDAD SOCIAL, SEG\u00daN ESTA ENCUESTA? - 103.9 fm","og_description":"El estudio se desarroll\u00f3 entre el 12 y el 16 de junio, a m\u00e1s de 1200 personas, residentes en el \u00c1rea Metropolitana de Buenos Aires, todos mayores de 16 a\u00f1os y al respecto, se obtuvieron los siguientes resultados: Fuente: Consultora Clivajes Cabe destacar que este 28 se vence la \u00faltima pr\u00f3rroga de la cuarentena decretada [&hellip;]","og_url":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/","og_site_name":"103.9 fm","article_publisher":"https:\/\/www.facebook.com\/ondauno103.9","article_published_time":"2020-06-23T23:16:01+00:00","article_modified_time":"2020-06-23T23:16:04+00:00","og_image":[{"width":973,"height":543,"url":"https:\/\/ondauno.com.ar\/wp-content\/uploads\/2020\/06\/Sin-t\u00edtulo1-1.png","type":"image\/png"}],"author":"fernando garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fernando garcia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/","url":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/","name":"\u00bfEST\u00c1 LISTO EL PA\u00cdS PARA LEVANTAR LA CUARENTENA Y APELAR A LA RESPONSABILIDAD SOCIAL, SEG\u00daN ESTA ENCUESTA? - 103.9 fm","isPartOf":{"@id":"https:\/\/ondauno.com.ar\/#website"},"datePublished":"2020-06-23T23:16:01+00:00","dateModified":"2020-06-23T23:16:04+00:00","author":{"@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139"},"breadcrumb":{"@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ondauno.com.ar\/index.php\/2020\/06\/23\/esta-listo-el-pais-para-levantar-la-cuarentena-y-apelar-a-la-responsabilidad-social-segun-esta-encuesta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ondauno.com.ar\/"},{"@type":"ListItem","position":2,"name":"\u00bfEST\u00c1 LISTO EL PA\u00cdS PARA LEVANTAR LA CUARENTENA Y APELAR A LA RESPONSABILIDAD SOCIAL, SEG\u00daN ESTA ENCUESTA?"}]},{"@type":"WebSite","@id":"https:\/\/ondauno.com.ar\/#website","url":"https:\/\/ondauno.com.ar\/","name":"103.9 fm","description":"LA PRIMERA RADIO MULTIMEDIA DE TRES ARROYOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ondauno.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/201d1b68e6c75e0fd396fe5f8af5d139","name":"fernando garcia","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ondauno.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7254642ad81272e79a2e69653cfdfc?s=96&d=mm&r=g","caption":"fernando garcia"},"url":"https:\/\/ondauno.com.ar\/index.php\/author\/ondaunoeditor\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11536"}],"version-history":[{"count":0,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11536\/revisions"}],"wp:attachment":[{"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ondauno.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}